{"id":5912,"date":"2025-09-20T19:47:56","date_gmt":"2025-09-20T19:47:56","guid":{"rendered":"https:\/\/radioecoutefm.com\/?p=5912"},"modified":"2025-09-20T19:47:56","modified_gmt":"2025-09-20T19:47:56","slug":"les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti","status":"publish","type":"post","link":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/","title":{"rendered":"Les \u00c9tats-Unis interceptent plus de 23 000 armes et stup\u00e9fiants destin\u00e9s \u00e0 Ha\u00efti"},"content":{"rendered":"<p>Les services d\u2019enqu\u00eate de la s\u00e9curit\u00e9 int\u00e9rieure des \u00c9tats-Unis (HSI) ont annonc\u00e9 avoir saisi, au cours de cette ann\u00e9e, plus de 23 000 armes et une importante quantit\u00e9 de stup\u00e9fiants en direction d\u2019Ha\u00efti. La valeur totale de ces marchandises illicites est estim\u00e9e \u00e0 plus d\u2019un million de dollars am\u00e9ricains.<\/p>\n<p>Cette op\u00e9ration s\u2019inscrit dans le cadre des efforts de Washington pour freiner le trafic d\u2019armes et de drogues qui alimente l\u2019ins\u00e9curit\u00e9 en Ha\u00efti. Selon les autorit\u00e9s am\u00e9ricaines, ce travail de surveillance et d\u2019interception restera une priorit\u00e9 afin d\u2019emp\u00eacher que ces cargaisons ne parviennent aux r\u00e9seaux criminels op\u00e9rant dans le pays.<\/p>\n<p>Les \u00c9tats-Unis ont par ailleurs r\u00e9affirm\u00e9 leur engagement \u00e0 poursuivre la coop\u00e9ration avec Ha\u00efti dans la lutte contre ce fl\u00e9au. \u00ab La s\u00e9curit\u00e9 d\u2019Ha\u00efti est importante pour les \u00c9tats-Unis \u00bb, ont soulign\u00e9 les responsables, insistant sur la n\u00e9cessit\u00e9 d\u2019un partenariat solide pour endiguer les trafics qui aggravent la crise s\u00e9curitaire ha\u00eftienne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les services d\u2019enqu\u00eate de la s\u00e9curit\u00e9 int\u00e9rieure des \u00c9tats-Unis (HSI) ont annonc\u00e9 avoir saisi, au cours de cette ann\u00e9e, plus de 23 000 armes et une importante quantit\u00e9 de stup\u00e9fiants en direction d\u2019Ha\u00efti. La valeur totale de ces marchandises illicites est estim\u00e9e \u00e0 plus d\u2019un million de dollars am\u00e9ricains. Cette op\u00e9ration s\u2019inscrit dans le cadre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[57,46],"tags":[],"ppma_author":[15],"class_list":["post-5912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-securite","category-international"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Les services d\u2019enqu\u00eate de la s\u00e9curit\u00e9 int\u00e9rieure des \u00c9tats-Unis (HSI) ont annonc\u00e9 avoir saisi, au cours de cette ann\u00e9e, plus de 23 000 armes et une importante quantit\u00e9 de stup\u00e9fiants en direction d\u2019Ha\u00efti. La valeur totale de ces marchandises illicites est estim\u00e9e \u00e0 plus d\u2019un million de dollars am\u00e9ricains. Cette op\u00e9ration s\u2019inscrit dans le cadre\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Ecoute FM\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"RADIO ECOUTE FM \u2013 La Radio de toutes les ecoutes\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Les \u00c9tats-Unis interceptent plus de 23 000 armes et stup\u00e9fiants destin\u00e9s \u00e0 Ha\u00efti \u2013 RADIO ECOUTE FM\" \/>\n\t\t<meta property=\"og:description\" content=\"Les services d\u2019enqu\u00eate de la s\u00e9curit\u00e9 int\u00e9rieure des \u00c9tats-Unis (HSI) ont annonc\u00e9 avoir saisi, au cours de cette ann\u00e9e, plus de 23 000 armes et une importante quantit\u00e9 de stup\u00e9fiants en direction d\u2019Ha\u00efti. La valeur totale de ces marchandises illicites est estim\u00e9e \u00e0 plus d\u2019un million de dollars am\u00e9ricains. Cette op\u00e9ration s\u2019inscrit dans le cadre\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1175\" \/>\n\t\t<meta property=\"og:image:height\" content=\"985\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-09-20T19:47:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-09-20T19:47:56+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Les \u00c9tats-Unis interceptent plus de 23 000 armes et stup\u00e9fiants destin\u00e9s \u00e0 Ha\u00efti \u2013 RADIO ECOUTE FM\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Les services d\u2019enqu\u00eate de la s\u00e9curit\u00e9 int\u00e9rieure des \u00c9tats-Unis (HSI) ont annonc\u00e9 avoir saisi, au cours de cette ann\u00e9e, plus de 23 000 armes et une importante quantit\u00e9 de stup\u00e9fiants en direction d\u2019Ha\u00efti. La valeur totale de ces marchandises illicites est estim\u00e9e \u00e0 plus d\u2019un million de dollars am\u00e9ricains. Cette op\u00e9ration s\u2019inscrit dans le cadre\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/20\\\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\\\/#blogposting\",\"name\":\"Les \\u00c9tats-Unis interceptent plus de 23 000 armes et stup\\u00e9fiants destin\\u00e9s \\u00e0 Ha\\u00efti \\u2013 RADIO ECOUTE FM\",\"headline\":\"Les \\u00c9tats-Unis interceptent plus de 23 000 armes et stup\\u00e9fiants destin\\u00e9s \\u00e0 Ha\\u00efti\",\"author\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radioecoutefm.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg?fit=1175%2C985&ssl=1\",\"width\":1175,\"height\":985},\"datePublished\":\"2025-09-20T19:47:56+00:00\",\"dateModified\":\"2025-09-20T19:47:56+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/20\\\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/20\\\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\\\/#webpage\"},\"articleSection\":\"INSECURITE, INTERNATIONAL, Ecoute FM\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/20\\\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/radioecoutefm.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/category\\\/international\\\/#listItem\",\"name\":\"INTERNATIONAL\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/category\\\/international\\\/#listItem\",\"position\":2,\"name\":\"INTERNATIONAL\",\"item\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/category\\\/international\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/20\\\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\\\/#listItem\",\"name\":\"Les \\u00c9tats-Unis interceptent plus de 23 000 armes et stup\\u00e9fiants destin\\u00e9s \\u00e0 Ha\\u00efti\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/20\\\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\\\/#listItem\",\"position\":3,\"name\":\"Les \\u00c9tats-Unis interceptent plus de 23 000 armes et stup\\u00e9fiants destin\\u00e9s \\u00e0 Ha\\u00efti\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/category\\\/international\\\/#listItem\",\"name\":\"INTERNATIONAL\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#organization\",\"name\":\"RADIO ECOUTE FM\",\"description\":\"La Radio de toutes les ecoutes\",\"url\":\"https:\\\/\\\/radioecoutefm.com\\\/\",\"email\":\"info@radioecoutefm.com\",\"telephone\":\"+15142173553\",\"foundingDate\":\"2019-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":0,\"maxValue\":9},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radioecoutefm.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-ECOIUTE1.png?fit=1600%2C800&ssl=1\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/20\\\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\\\/#organizationLogo\",\"width\":1600,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/20\\\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/#author\",\"url\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/\",\"name\":\"Ecoute FM\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/20\\\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5369629745bf29c5deb65198d5e38aed1dc2c880c04b3b630ab3f6e8c623b70?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Ecoute FM\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/20\\\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\\\/#webpage\",\"url\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/20\\\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\\\/\",\"name\":\"Les \\u00c9tats-Unis interceptent plus de 23 000 armes et stup\\u00e9fiants destin\\u00e9s \\u00e0 Ha\\u00efti \\u2013 RADIO ECOUTE FM\",\"description\":\"Les services d\\u2019enqu\\u00eate de la s\\u00e9curit\\u00e9 int\\u00e9rieure des \\u00c9tats-Unis (HSI) ont annonc\\u00e9 avoir saisi, au cours de cette ann\\u00e9e, plus de 23 000 armes et une importante quantit\\u00e9 de stup\\u00e9fiants en direction d\\u2019Ha\\u00efti. La valeur totale de ces marchandises illicites est estim\\u00e9e \\u00e0 plus d\\u2019un million de dollars am\\u00e9ricains. Cette op\\u00e9ration s\\u2019inscrit dans le cadre\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/20\\\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radioecoutefm.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg?fit=1175%2C985&ssl=1\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/20\\\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\\\/#mainImage\",\"width\":1175,\"height\":985},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/20\\\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\\\/#mainImage\"},\"datePublished\":\"2025-09-20T19:47:56+00:00\",\"dateModified\":\"2025-09-20T19:47:56+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#website\",\"url\":\"https:\\\/\\\/radioecoutefm.com\\\/\",\"name\":\"RADIO ECOUTE FM\",\"alternateName\":\"Ecoute FM\",\"description\":\"La Radio de toutes les ecoutes\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Les \u00c9tats-Unis interceptent plus de 23 000 armes et stup\u00e9fiants destin\u00e9s \u00e0 Ha\u00efti \u2013 RADIO ECOUTE FM","description":"Les services d\u2019enqu\u00eate de la s\u00e9curit\u00e9 int\u00e9rieure des \u00c9tats-Unis (HSI) ont annonc\u00e9 avoir saisi, au cours de cette ann\u00e9e, plus de 23 000 armes et une importante quantit\u00e9 de stup\u00e9fiants en direction d\u2019Ha\u00efti. La valeur totale de ces marchandises illicites est estim\u00e9e \u00e0 plus d\u2019un million de dollars am\u00e9ricains. Cette op\u00e9ration s\u2019inscrit dans le cadre","canonical_url":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/#blogposting","name":"Les \u00c9tats-Unis interceptent plus de 23 000 armes et stup\u00e9fiants destin\u00e9s \u00e0 Ha\u00efti \u2013 RADIO ECOUTE FM","headline":"Les \u00c9tats-Unis interceptent plus de 23 000 armes et stup\u00e9fiants destin\u00e9s \u00e0 Ha\u00efti","author":{"@id":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/#author"},"publisher":{"@id":"https:\/\/radioecoutefm.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg?fit=1175%2C985&ssl=1","width":1175,"height":985},"datePublished":"2025-09-20T19:47:56+00:00","dateModified":"2025-09-20T19:47:56+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/#webpage"},"isPartOf":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/#webpage"},"articleSection":"INSECURITE, INTERNATIONAL, Ecoute FM"},{"@type":"BreadcrumbList","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com#listItem","position":1,"name":"Home","item":"https:\/\/radioecoutefm.com","nextItem":{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/#listItem","name":"INTERNATIONAL"}},{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/#listItem","position":2,"name":"INTERNATIONAL","item":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/","nextItem":{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/#listItem","name":"Les \u00c9tats-Unis interceptent plus de 23 000 armes et stup\u00e9fiants destin\u00e9s \u00e0 Ha\u00efti"},"previousItem":{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/#listItem","position":3,"name":"Les \u00c9tats-Unis interceptent plus de 23 000 armes et stup\u00e9fiants destin\u00e9s \u00e0 Ha\u00efti","previousItem":{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/#listItem","name":"INTERNATIONAL"}}]},{"@type":"Organization","@id":"https:\/\/radioecoutefm.com\/#organization","name":"RADIO ECOUTE FM","description":"La Radio de toutes les ecoutes","url":"https:\/\/radioecoutefm.com\/","email":"info@radioecoutefm.com","telephone":"+15142173553","foundingDate":"2019-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":0,"maxValue":9},"logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2022\/02\/cropped-ECOIUTE1.png?fit=1600%2C800&ssl=1","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/#organizationLogo","width":1600,"height":800},"image":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/#author","url":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/","name":"Ecoute FM","image":{"@type":"ImageObject","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a5369629745bf29c5deb65198d5e38aed1dc2c880c04b3b630ab3f6e8c623b70?s=96&d=mm&r=g","width":96,"height":96,"caption":"Ecoute FM"}},{"@type":"WebPage","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/#webpage","url":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/","name":"Les \u00c9tats-Unis interceptent plus de 23 000 armes et stup\u00e9fiants destin\u00e9s \u00e0 Ha\u00efti \u2013 RADIO ECOUTE FM","description":"Les services d\u2019enqu\u00eate de la s\u00e9curit\u00e9 int\u00e9rieure des \u00c9tats-Unis (HSI) ont annonc\u00e9 avoir saisi, au cours de cette ann\u00e9e, plus de 23 000 armes et une importante quantit\u00e9 de stup\u00e9fiants en direction d\u2019Ha\u00efti. La valeur totale de ces marchandises illicites est estim\u00e9e \u00e0 plus d\u2019un million de dollars am\u00e9ricains. Cette op\u00e9ration s\u2019inscrit dans le cadre","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/radioecoutefm.com\/#website"},"breadcrumb":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/#breadcrumblist"},"author":{"@id":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/#author"},"creator":{"@id":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg?fit=1175%2C985&ssl=1","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/#mainImage","width":1175,"height":985},"primaryImageOfPage":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/#mainImage"},"datePublished":"2025-09-20T19:47:56+00:00","dateModified":"2025-09-20T19:47:56+00:00"},{"@type":"WebSite","@id":"https:\/\/radioecoutefm.com\/#website","url":"https:\/\/radioecoutefm.com\/","name":"RADIO ECOUTE FM","alternateName":"Ecoute FM","description":"La Radio de toutes les ecoutes","inLanguage":"en-US","publisher":{"@id":"https:\/\/radioecoutefm.com\/#organization"}}]},"og:locale":"en_US","og:site_name":"RADIO ECOUTE FM \u2013 La Radio de toutes les ecoutes","og:type":"article","og:title":"Les \u00c9tats-Unis interceptent plus de 23 000 armes et stup\u00e9fiants destin\u00e9s \u00e0 Ha\u00efti \u2013 RADIO ECOUTE FM","og:description":"Les services d\u2019enqu\u00eate de la s\u00e9curit\u00e9 int\u00e9rieure des \u00c9tats-Unis (HSI) ont annonc\u00e9 avoir saisi, au cours de cette ann\u00e9e, plus de 23 000 armes et une importante quantit\u00e9 de stup\u00e9fiants en direction d\u2019Ha\u00efti. La valeur totale de ces marchandises illicites est estim\u00e9e \u00e0 plus d\u2019un million de dollars am\u00e9ricains. Cette op\u00e9ration s\u2019inscrit dans le cadre","og:url":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/","og:image":"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg","og:image:secure_url":"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg","og:image:width":1175,"og:image:height":985,"article:published_time":"2025-09-20T19:47:56+00:00","article:modified_time":"2025-09-20T19:47:56+00:00","twitter:card":"summary_large_image","twitter:title":"Les \u00c9tats-Unis interceptent plus de 23 000 armes et stup\u00e9fiants destin\u00e9s \u00e0 Ha\u00efti \u2013 RADIO ECOUTE FM","twitter:description":"Les services d\u2019enqu\u00eate de la s\u00e9curit\u00e9 int\u00e9rieure des \u00c9tats-Unis (HSI) ont annonc\u00e9 avoir saisi, au cours de cette ann\u00e9e, plus de 23 000 armes et une importante quantit\u00e9 de stup\u00e9fiants en direction d\u2019Ha\u00efti. La valeur totale de ces marchandises illicites est estim\u00e9e \u00e0 plus d\u2019un million de dollars am\u00e9ricains. Cette op\u00e9ration s\u2019inscrit dans le cadre","twitter:image":"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg"},"aioseo_meta_data":{"post_id":"5912","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-09-20 19:47:58","updated":"2025-09-20 19:51:59","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/radioecoutefm.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/radioecoutefm.com\/index.php\/category\/international\/\" title=\"INTERNATIONAL\">INTERNATIONAL<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLes \u00c9tats-Unis interceptent plus de 23 000 armes et stup\u00e9fiants destin\u00e9s \u00e0 Ha\u00efti\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/radioecoutefm.com"},{"label":"INTERNATIONAL","link":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/"},{"label":"Les \u00c9tats-Unis interceptent plus de 23 000 armes et stup\u00e9fiants destin\u00e9s \u00e0 Ha\u00efti","link":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/20\/les-etats-unis-interceptent-plus-de-23-000-armes-et-stupefiants-destines-a-haiti\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg?fit=1175%2C985&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg?fit=1175%2C985&ssl=1",1175,985,false],"thumbnail":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg?fit=300%2C251&ssl=1",300,251,true],"medium_large":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg?fit=640%2C537&ssl=1",640,537,true],"large":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg?fit=640%2C536&ssl=1",640,536,true],"1536x1536":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg?fit=1175%2C985&ssl=1",1175,985,true],"2048x2048":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg?fit=1175%2C985&ssl=1",1175,985,true],"newsair-slider-full":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg?resize=1175%2C720&ssl=1",1175,720,true],"newsair-featured":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg?fit=1024%2C858&ssl=1",1024,858,true],"newsair-medium":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/6A28D815-1BD7-4253-89CB-B49527820730.jpeg?resize=720%2C380&ssl=1",720,380,true]},"uagb_author_info":{"display_name":"Ecoute FM","author_link":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/"},"uagb_comment_info":2,"uagb_excerpt":"Les services d\u2019enqu\u00eate de la s\u00e9curit\u00e9 int\u00e9rieure des \u00c9tats-Unis (HSI) ont annonc\u00e9 avoir saisi, au cours de cette ann\u00e9e, plus de 23 000 armes et une importante quantit\u00e9 de stup\u00e9fiants en direction d\u2019Ha\u00efti. La valeur totale de ces marchandises illicites est estim\u00e9e \u00e0 plus d\u2019un million de dollars am\u00e9ricains. Cette op\u00e9ration s\u2019inscrit dans le cadre&hellip;","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pgoyna-1xm","jetpack-related-posts":[{"id":303,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/02\/21\/securite-en-haiti-les-etats-unis-renforcent-la-capacite-de-la-mission-multinationale-avec-20-vehicules-blindes\/","url_meta":{"origin":5912,"position":0},"title":"S\u00e9curit\u00e9 en Ha\u00efti : Les \u00c9tats-Unis renforcent la capacit\u00e9 de la Mission multinationale avec 20 v\u00e9hicules blind\u00e9s","author":"Ecoute FM","date":"21.02.2025","format":false,"excerpt":"Le Bureau des affaires internationales de stup\u00e9fiants et d\u2019application de la loi (INL) des \u00c9tats-Unis a annonc\u00e9 la livraison de 20 v\u00e9hicules blind\u00e9s de transport de troupes \u00e0 la Mission multinationale d\u2019Appui \u00e0 la S\u00e9curit\u00e9 (MMAS) en Ha\u00efti. Cette initiative fait partie d\u2019un engagement continu pour renforcer la s\u00e9curit\u00e9 du\u2026","rel":"","context":"In &quot;POLITIQUE&quot;","block_context":{"text":"POLITIQUE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/politique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/02\/mssp.jpeg?fit=1062%2C563&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/02\/mssp.jpeg?fit=1062%2C563&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/02\/mssp.jpeg?fit=1062%2C563&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/02\/mssp.jpeg?fit=1062%2C563&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/02\/mssp.jpeg?fit=1062%2C563&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1720,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/03\/17\/trafic-darmes-en-haiti-la-floride-un-carrefour-cle-de-lapprovisionnement-des-gangs\/","url_meta":{"origin":5912,"position":1},"title":"Trafic d\u2019armes en Ha\u00efti : la Floride, un carrefour cl\u00e9 de l\u2019approvisionnement des gangs","author":"Ecoute FM","date":"17.03.2025","format":false,"excerpt":"Le trafic d\u2019armes et de munitions continue d\u2019alimenter la spirale de violence en Ha\u00efti, facilitant l\u2019expansion des gangs criminels qui terrorisent la population. Selon William O\u2019Neill, expert ind\u00e9pendant des Nations Unies en droits de l\u2019homme sur Ha\u00efti, l\u2019une des solutions les plus efficaces pour d\u00e9manteler ces groupes arm\u00e9s serait de\u2026","rel":"","context":"In &quot;INSECURITE&quot;","block_context":{"text":"INSECURITE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/securite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/IMG_1408.jpeg?fit=1170%2C551&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/IMG_1408.jpeg?fit=1170%2C551&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/IMG_1408.jpeg?fit=1170%2C551&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/IMG_1408.jpeg?fit=1170%2C551&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/IMG_1408.jpeg?fit=1170%2C551&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6103,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/10\/10\/les-etats-unis-livrent-des-vehicules-blindes-pour-renforcer-la-force-de-repression-des-gangs-en-haiti\/","url_meta":{"origin":5912,"position":2},"title":"Les \u00c9tats-Unis livrent des v\u00e9hicules blind\u00e9s pour renforcer la Force de R\u00e9pression des Gangs en Ha\u00efti","author":"Ecoute FM","date":"10.10.2025","format":false,"excerpt":"Les \u00c9tats-Unis ont proc\u00e9d\u00e9, cette semaine, \u00e0 la livraison d\u2019un nouveau lot de v\u00e9hicules blind\u00e9s destin\u00e9s au gouvernement ha\u00eftien. Ces \u00e9quipements viennent appuyer la Force de R\u00e9pression des Gangs (FRG) ainsi que la Police nationale d\u2019Ha\u00efti (PNH) dans leur lutte contre les groupes arm\u00e9s qui continuent de semer la terreur\u2026","rel":"","context":"In &quot;SECURITE&quot;","block_context":{"text":"SECURITE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/insecurite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/10\/cha.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/10\/cha.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/10\/cha.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/10\/cha.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3782,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/05\/04\/les-etats-unis-discutent-avec-loea-pour-le-deploiement-de-troupes-latino-americaines-en-haiti\/","url_meta":{"origin":5912,"position":3},"title":"Les \u00c9tats-Unis discutent avec l\u2019OEA pour le d\u00e9ploiement de troupes latino-am\u00e9ricaines en Ha\u00efti","author":"Ecoute FM","date":"04.05.2025","format":false,"excerpt":"Face \u00e0 la d\u00e9gradation alarmante de la situation s\u00e9curitaire en Ha\u00efti, les \u00c9tats-Unis ont engag\u00e9 des pourparlers avec l\u2019Organisation des \u00c9tats Am\u00e9ricains (OEA) pour coordonner le d\u00e9ploiement de troupes issues de pays d\u2019Am\u00e9rique latine. L\u2019objectif de cette initiative est de contenir l\u2019influence croissante des gangs arm\u00e9s qui contr\u00f4lent de vastes\u2026","rel":"","context":"In &quot;INTERNATIONAL&quot;","block_context":{"text":"INTERNATIONAL","link":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1923,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/03\/22\/les-etats-unis-mettent-fin-aux-programmes-de-parole-humanitaire-pour-les-migrants-de-cuba-haiti-nicaragua-et-venezuela\/","url_meta":{"origin":5912,"position":4},"title":"Les \u00c9tats-Unis mettent fin aux programmes de parole humanitaire pour les migrants de Cuba, Ha\u00efti, Nicaragua et Venezuela","author":"Ecoute FM","date":"22.03.2025","format":false,"excerpt":"Le Department of Homeland Security (DHS) des \u00c9tats-Unis a annonc\u00e9 la suppression des programmes de parole humanitaire pour les citoyens de Cuba, Ha\u00efti, Nicaragua et Venezuela, ainsi que leurs familles imm\u00e9diates. Connus sous le nom de programmes CHNV, ils permettaient aux migrants d\u2019entrer temporairement aux \u00c9tats-Unis pour des raisons humanitaires\u2026","rel":"","context":"In &quot;POLITIQUE&quot;","block_context":{"text":"POLITIQUE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/politique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/IMG_1449.jpeg?fit=1170%2C511&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/IMG_1449.jpeg?fit=1170%2C511&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/IMG_1449.jpeg?fit=1170%2C511&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/IMG_1449.jpeg?fit=1170%2C511&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/IMG_1449.jpeg?fit=1170%2C511&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3081,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/04\/18\/viv-ansanm-et-gran-grif-dans-le-viseur-des-etats-unis-vers-une-reponse-antiterroriste\/","url_meta":{"origin":5912,"position":5},"title":"Viv Ansanm et Gran Grif dans le viseur des \u00c9tats-Unis, vers une r\u00e9ponse antiterroriste","author":"Ecoute FM","date":"18.04.2025","format":false,"excerpt":"Les gangs arm\u00e9s qui s\u00e8ment la terreur en Ha\u00efti pourraient bient\u00f4t \u00eatre officiellement reconnus comme des organisations terroristes \u00e9trang\u00e8res par le gouvernement am\u00e9ricain. Cette mesure viserait notamment la coalition Viv Ansanm et le groupe Gran Grif, actifs \u00e0 Port-au-Prince et dans la r\u00e9gion de l\u2019Artibonite. Selon un article du Miami\u2026","rel":"","context":"In &quot;INSECURITE&quot;","block_context":{"text":"INSECURITE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/securite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/04\/IMG_1729.jpeg?fit=1110%2C740&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/04\/IMG_1729.jpeg?fit=1110%2C740&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/04\/IMG_1729.jpeg?fit=1110%2C740&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/04\/IMG_1729.jpeg?fit=1110%2C740&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/04\/IMG_1729.jpeg?fit=1110%2C740&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"authors":[{"term_id":15,"user_id":1,"is_guest":0,"slug":"borgellaattis","display_name":"Ecoute FM","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/a5369629745bf29c5deb65198d5e38aed1dc2c880c04b3b630ab3f6e8c623b70?s=96&d=mm&r=g","author_category":"","first_name":"","last_name":"","user_url":"http:\/\/radioecoutefm.com","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/posts\/5912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/comments?post=5912"}],"version-history":[{"count":1,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/posts\/5912\/revisions"}],"predecessor-version":[{"id":5917,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/posts\/5912\/revisions\/5917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/media\/5913"}],"wp:attachment":[{"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/media?parent=5912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/categories?post=5912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/tags?post=5912"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/ppma_author?post=5912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}