{"id":5894,"date":"2025-09-19T16:04:44","date_gmt":"2025-09-19T16:04:44","guid":{"rendered":"https:\/\/radioecoutefm.com\/?p=5894"},"modified":"2025-09-19T16:04:44","modified_gmt":"2025-09-19T16:04:44","slug":"necrologie-deces-de-lancien-senateur-dejean-belizaire","status":"publish","type":"post","link":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/","title":{"rendered":"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire"},"content":{"rendered":"<p>N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire<\/p>\n<p>L\u2019ancien s\u00e9nateur et homme politique ha\u00eftien D\u00e9jean B\u00e9lizaire est d\u00e9c\u00e9d\u00e9 ce jeudi \u00e0 New York \u00e0 l\u2019\u00e2ge de 90 ans, selon des sources familiales. Ing\u00e9nieur de formation, sp\u00e9cialiste en hydrologie et hydraulique, il \u00e9tait originaire de Petite-Rivi\u00e8re-de-l\u2019Artibonite, o\u00f9 il \u00e9tait n\u00e9 en 1935.<\/p>\n<p>Figure marquante de la vie politique nationale, D\u00e9jean B\u00e9lizaire avait d\u2019abord \u00e9t\u00e9 un dirigeant \u00e9tudiant dans les ann\u00e9es 1950, avant de se tourner vers une carri\u00e8re technique \u00e0 l\u2019\u00e9tranger. Rentr\u00e9 en Ha\u00efti, il devient l\u2019un des leaders du Mouvement National Patriotique du 28 Novembre (MNP-28). \u00c9lu s\u00e9nateur en 1990, il est acc\u00e9d\u00e9 \u00e0 la pr\u00e9sidence de l\u2019Assembl\u00e9e nationale le 29 ao\u00fbt 1992, dans un contexte marqu\u00e9 par l\u2019instabilit\u00e9 politique cons\u00e9cutive au coup d\u2019\u00c9tat contre le pr\u00e9sident Jean-Bertrand Aristide.<\/p>\n<p>Engag\u00e9 dans les d\u00e9bats sur la transition d\u00e9mocratique, M. B\u00e9lizaire fut \u00e9galement candidat \u00e0 la pr\u00e9sidence provisoire en 2016, lors de l\u2019\u00e9lection parlementaire qui porta Jocelerme Privert au pouvoir. Sa disparition met fin au parcours d\u2019un acteur politique ayant marqu\u00e9 plusieurs d\u00e9cennies de la vie publique ha\u00eftienne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire L\u2019ancien s\u00e9nateur et homme politique ha\u00eftien D\u00e9jean B\u00e9lizaire est d\u00e9c\u00e9d\u00e9 ce jeudi \u00e0 New York \u00e0 l\u2019\u00e2ge de 90 ans, selon des sources familiales. Ing\u00e9nieur de formation, sp\u00e9cialiste en hydrologie et hydraulique, il \u00e9tait originaire de Petite-Rivi\u00e8re-de-l\u2019Artibonite, o\u00f9 il \u00e9tait n\u00e9 en 1935. Figure marquante de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5895,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[62],"tags":[],"ppma_author":[15],"class_list":["post-5894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-necrologie"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire L\u2019ancien s\u00e9nateur et homme politique ha\u00eftien D\u00e9jean B\u00e9lizaire est d\u00e9c\u00e9d\u00e9 ce jeudi \u00e0 New York \u00e0 l\u2019\u00e2ge de 90 ans, selon des sources familiales. Ing\u00e9nieur de formation, sp\u00e9cialiste en hydrologie et hydraulique, il \u00e9tait originaire de Petite-Rivi\u00e8re-de-l\u2019Artibonite, o\u00f9 il \u00e9tait n\u00e9 en 1935. Figure marquante de la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Ecoute FM\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"RADIO ECOUTE FM \u2013 La Radio de toutes les ecoutes\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire \u2013 RADIO ECOUTE FM\" \/>\n\t\t<meta property=\"og:description\" content=\"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire L\u2019ancien s\u00e9nateur et homme politique ha\u00eftien D\u00e9jean B\u00e9lizaire est d\u00e9c\u00e9d\u00e9 ce jeudi \u00e0 New York \u00e0 l\u2019\u00e2ge de 90 ans, selon des sources familiales. Ing\u00e9nieur de formation, sp\u00e9cialiste en hydrologie et hydraulique, il \u00e9tait originaire de Petite-Rivi\u00e8re-de-l\u2019Artibonite, o\u00f9 il \u00e9tait n\u00e9 en 1935. Figure marquante de la\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t\t<meta property=\"og:image:height\" content=\"367\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-09-19T16:04:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-09-19T16:04:44+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire \u2013 RADIO ECOUTE FM\" \/>\n\t\t<meta name=\"twitter:description\" content=\"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire L\u2019ancien s\u00e9nateur et homme politique ha\u00eftien D\u00e9jean B\u00e9lizaire est d\u00e9c\u00e9d\u00e9 ce jeudi \u00e0 New York \u00e0 l\u2019\u00e2ge de 90 ans, selon des sources familiales. Ing\u00e9nieur de formation, sp\u00e9cialiste en hydrologie et hydraulique, il \u00e9tait originaire de Petite-Rivi\u00e8re-de-l\u2019Artibonite, o\u00f9 il \u00e9tait n\u00e9 en 1935. Figure marquante de la\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/19\\\/necrologie-deces-de-lancien-senateur-dejean-belizaire\\\/#blogposting\",\"name\":\"N\\u00e9crologie : D\\u00e9c\\u00e8s de l\\u2019ancien s\\u00e9nateur D\\u00e9jean B\\u00e9lizaire \\u2013 RADIO ECOUTE FM\",\"headline\":\"N\\u00e9crologie : D\\u00e9c\\u00e8s de l\\u2019ancien s\\u00e9nateur D\\u00e9jean B\\u00e9lizaire\",\"author\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radioecoutefm.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg?fit=550%2C367&ssl=1\",\"width\":550,\"height\":367},\"datePublished\":\"2025-09-19T16:04:44+00:00\",\"dateModified\":\"2025-09-19T16:04:44+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/19\\\/necrologie-deces-de-lancien-senateur-dejean-belizaire\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/19\\\/necrologie-deces-de-lancien-senateur-dejean-belizaire\\\/#webpage\"},\"articleSection\":\"NECROLOGIE, Ecoute FM\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/19\\\/necrologie-deces-de-lancien-senateur-dejean-belizaire\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/radioecoutefm.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/category\\\/necrologie\\\/#listItem\",\"name\":\"NECROLOGIE\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/category\\\/necrologie\\\/#listItem\",\"position\":2,\"name\":\"NECROLOGIE\",\"item\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/category\\\/necrologie\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/19\\\/necrologie-deces-de-lancien-senateur-dejean-belizaire\\\/#listItem\",\"name\":\"N\\u00e9crologie : D\\u00e9c\\u00e8s de l\\u2019ancien s\\u00e9nateur D\\u00e9jean B\\u00e9lizaire\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/19\\\/necrologie-deces-de-lancien-senateur-dejean-belizaire\\\/#listItem\",\"position\":3,\"name\":\"N\\u00e9crologie : D\\u00e9c\\u00e8s de l\\u2019ancien s\\u00e9nateur D\\u00e9jean B\\u00e9lizaire\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/category\\\/necrologie\\\/#listItem\",\"name\":\"NECROLOGIE\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#organization\",\"name\":\"RADIO ECOUTE FM\",\"description\":\"La Radio de toutes les ecoutes\",\"url\":\"https:\\\/\\\/radioecoutefm.com\\\/\",\"email\":\"info@radioecoutefm.com\",\"telephone\":\"+15142173553\",\"foundingDate\":\"2019-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":0,\"maxValue\":9},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radioecoutefm.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-ECOIUTE1.png?fit=1600%2C800&ssl=1\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/19\\\/necrologie-deces-de-lancien-senateur-dejean-belizaire\\\/#organizationLogo\",\"width\":1600,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/19\\\/necrologie-deces-de-lancien-senateur-dejean-belizaire\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/#author\",\"url\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/\",\"name\":\"Ecoute FM\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/19\\\/necrologie-deces-de-lancien-senateur-dejean-belizaire\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5369629745bf29c5deb65198d5e38aed1dc2c880c04b3b630ab3f6e8c623b70?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Ecoute FM\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/19\\\/necrologie-deces-de-lancien-senateur-dejean-belizaire\\\/#webpage\",\"url\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/19\\\/necrologie-deces-de-lancien-senateur-dejean-belizaire\\\/\",\"name\":\"N\\u00e9crologie : D\\u00e9c\\u00e8s de l\\u2019ancien s\\u00e9nateur D\\u00e9jean B\\u00e9lizaire \\u2013 RADIO ECOUTE FM\",\"description\":\"N\\u00e9crologie : D\\u00e9c\\u00e8s de l\\u2019ancien s\\u00e9nateur D\\u00e9jean B\\u00e9lizaire L\\u2019ancien s\\u00e9nateur et homme politique ha\\u00eftien D\\u00e9jean B\\u00e9lizaire est d\\u00e9c\\u00e9d\\u00e9 ce jeudi \\u00e0 New York \\u00e0 l\\u2019\\u00e2ge de 90 ans, selon des sources familiales. Ing\\u00e9nieur de formation, sp\\u00e9cialiste en hydrologie et hydraulique, il \\u00e9tait originaire de Petite-Rivi\\u00e8re-de-l\\u2019Artibonite, o\\u00f9 il \\u00e9tait n\\u00e9 en 1935. Figure marquante de la\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/19\\\/necrologie-deces-de-lancien-senateur-dejean-belizaire\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radioecoutefm.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg?fit=550%2C367&ssl=1\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/19\\\/necrologie-deces-de-lancien-senateur-dejean-belizaire\\\/#mainImage\",\"width\":550,\"height\":367},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/09\\\/19\\\/necrologie-deces-de-lancien-senateur-dejean-belizaire\\\/#mainImage\"},\"datePublished\":\"2025-09-19T16:04:44+00:00\",\"dateModified\":\"2025-09-19T16:04:44+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#website\",\"url\":\"https:\\\/\\\/radioecoutefm.com\\\/\",\"name\":\"RADIO ECOUTE FM\",\"alternateName\":\"Ecoute FM\",\"description\":\"La Radio de toutes les ecoutes\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire \u2013 RADIO ECOUTE FM","description":"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire L\u2019ancien s\u00e9nateur et homme politique ha\u00eftien D\u00e9jean B\u00e9lizaire est d\u00e9c\u00e9d\u00e9 ce jeudi \u00e0 New York \u00e0 l\u2019\u00e2ge de 90 ans, selon des sources familiales. Ing\u00e9nieur de formation, sp\u00e9cialiste en hydrologie et hydraulique, il \u00e9tait originaire de Petite-Rivi\u00e8re-de-l\u2019Artibonite, o\u00f9 il \u00e9tait n\u00e9 en 1935. Figure marquante de la","canonical_url":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/#blogposting","name":"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire \u2013 RADIO ECOUTE FM","headline":"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire","author":{"@id":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/#author"},"publisher":{"@id":"https:\/\/radioecoutefm.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg?fit=550%2C367&ssl=1","width":550,"height":367},"datePublished":"2025-09-19T16:04:44+00:00","dateModified":"2025-09-19T16:04:44+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/#webpage"},"isPartOf":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/#webpage"},"articleSection":"NECROLOGIE, Ecoute FM"},{"@type":"BreadcrumbList","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com#listItem","position":1,"name":"Home","item":"https:\/\/radioecoutefm.com","nextItem":{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/category\/necrologie\/#listItem","name":"NECROLOGIE"}},{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/category\/necrologie\/#listItem","position":2,"name":"NECROLOGIE","item":"https:\/\/radioecoutefm.com\/index.php\/category\/necrologie\/","nextItem":{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/#listItem","name":"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire"},"previousItem":{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/#listItem","position":3,"name":"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire","previousItem":{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/category\/necrologie\/#listItem","name":"NECROLOGIE"}}]},{"@type":"Organization","@id":"https:\/\/radioecoutefm.com\/#organization","name":"RADIO ECOUTE FM","description":"La Radio de toutes les ecoutes","url":"https:\/\/radioecoutefm.com\/","email":"info@radioecoutefm.com","telephone":"+15142173553","foundingDate":"2019-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":0,"maxValue":9},"logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2022\/02\/cropped-ECOIUTE1.png?fit=1600%2C800&ssl=1","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/#organizationLogo","width":1600,"height":800},"image":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/#author","url":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/","name":"Ecoute FM","image":{"@type":"ImageObject","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a5369629745bf29c5deb65198d5e38aed1dc2c880c04b3b630ab3f6e8c623b70?s=96&d=mm&r=g","width":96,"height":96,"caption":"Ecoute FM"}},{"@type":"WebPage","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/#webpage","url":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/","name":"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire \u2013 RADIO ECOUTE FM","description":"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire L\u2019ancien s\u00e9nateur et homme politique ha\u00eftien D\u00e9jean B\u00e9lizaire est d\u00e9c\u00e9d\u00e9 ce jeudi \u00e0 New York \u00e0 l\u2019\u00e2ge de 90 ans, selon des sources familiales. Ing\u00e9nieur de formation, sp\u00e9cialiste en hydrologie et hydraulique, il \u00e9tait originaire de Petite-Rivi\u00e8re-de-l\u2019Artibonite, o\u00f9 il \u00e9tait n\u00e9 en 1935. Figure marquante de la","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/radioecoutefm.com\/#website"},"breadcrumb":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/#breadcrumblist"},"author":{"@id":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/#author"},"creator":{"@id":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg?fit=550%2C367&ssl=1","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/#mainImage","width":550,"height":367},"primaryImageOfPage":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/#mainImage"},"datePublished":"2025-09-19T16:04:44+00:00","dateModified":"2025-09-19T16:04:44+00:00"},{"@type":"WebSite","@id":"https:\/\/radioecoutefm.com\/#website","url":"https:\/\/radioecoutefm.com\/","name":"RADIO ECOUTE FM","alternateName":"Ecoute FM","description":"La Radio de toutes les ecoutes","inLanguage":"en-US","publisher":{"@id":"https:\/\/radioecoutefm.com\/#organization"}}]},"og:locale":"en_US","og:site_name":"RADIO ECOUTE FM \u2013 La Radio de toutes les ecoutes","og:type":"article","og:title":"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire \u2013 RADIO ECOUTE FM","og:description":"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire L\u2019ancien s\u00e9nateur et homme politique ha\u00eftien D\u00e9jean B\u00e9lizaire est d\u00e9c\u00e9d\u00e9 ce jeudi \u00e0 New York \u00e0 l\u2019\u00e2ge de 90 ans, selon des sources familiales. Ing\u00e9nieur de formation, sp\u00e9cialiste en hydrologie et hydraulique, il \u00e9tait originaire de Petite-Rivi\u00e8re-de-l\u2019Artibonite, o\u00f9 il \u00e9tait n\u00e9 en 1935. Figure marquante de la","og:url":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/","og:image":"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg","og:image:secure_url":"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg","og:image:width":550,"og:image:height":367,"article:published_time":"2025-09-19T16:04:44+00:00","article:modified_time":"2025-09-19T16:04:44+00:00","twitter:card":"summary_large_image","twitter:title":"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire \u2013 RADIO ECOUTE FM","twitter:description":"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire L\u2019ancien s\u00e9nateur et homme politique ha\u00eftien D\u00e9jean B\u00e9lizaire est d\u00e9c\u00e9d\u00e9 ce jeudi \u00e0 New York \u00e0 l\u2019\u00e2ge de 90 ans, selon des sources familiales. Ing\u00e9nieur de formation, sp\u00e9cialiste en hydrologie et hydraulique, il \u00e9tait originaire de Petite-Rivi\u00e8re-de-l\u2019Artibonite, o\u00f9 il \u00e9tait n\u00e9 en 1935. Figure marquante de la","twitter:image":"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg"},"aioseo_meta_data":{"post_id":"5894","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-09-19 16:04:45","updated":"2025-09-19 16:17:42","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/radioecoutefm.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/radioecoutefm.com\/index.php\/category\/necrologie\/\" title=\"NECROLOGIE\">NECROLOGIE<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tN\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/radioecoutefm.com"},{"label":"NECROLOGIE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/necrologie\/"},{"label":"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire","link":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/19\/necrologie-deces-de-lancien-senateur-dejean-belizaire\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg?fit=550%2C367&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg?fit=550%2C367&ssl=1",550,367,false],"thumbnail":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg?fit=550%2C367&ssl=1",550,367,true],"large":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg?fit=550%2C367&ssl=1",550,367,true],"1536x1536":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg?fit=550%2C367&ssl=1",550,367,true],"2048x2048":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg?fit=550%2C367&ssl=1",550,367,true],"newsair-slider-full":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg?resize=550%2C367&ssl=1",550,367,true],"newsair-featured":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg?fit=550%2C367&ssl=1",550,367,true],"newsair-medium":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-18-at-18.19.10.jpeg?resize=550%2C367&ssl=1",550,367,true]},"uagb_author_info":{"display_name":"Ecoute FM","author_link":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/"},"uagb_comment_info":3,"uagb_excerpt":"N\u00e9crologie : D\u00e9c\u00e8s de l\u2019ancien s\u00e9nateur D\u00e9jean B\u00e9lizaire L\u2019ancien s\u00e9nateur et homme politique ha\u00eftien D\u00e9jean B\u00e9lizaire est d\u00e9c\u00e9d\u00e9 ce jeudi \u00e0 New York \u00e0 l\u2019\u00e2ge de 90 ans, selon des sources familiales. Ing\u00e9nieur de formation, sp\u00e9cialiste en hydrologie et hydraulique, il \u00e9tait originaire de Petite-Rivi\u00e8re-de-l\u2019Artibonite, o\u00f9 il \u00e9tait n\u00e9 en 1935. Figure marquante de la&hellip;","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pgoyna-1x4","jetpack-related-posts":[{"id":5958,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/23\/les-etats-unis-sanctionnent-don-kato-et-arnel-belizaire\/","url_meta":{"origin":5894,"position":0},"title":"Les \u00c9tats-Unis sanctionnent Don Kato et Arnel B\u00e9lizaire","author":"Ecoute FM","date":"23.09.2025","format":false,"excerpt":"Le D\u00e9partement d\u2019\u00c9tat am\u00e9ricain a annonc\u00e9 ce lundi 22 septembre des sanctions contre deux figures politiques ha\u00eftiennes. Il s'agit de l\u2019ancien s\u00e9nateur Antonio Ch\u00e9ramy, dit Don Kato, et l\u2019ancien d\u00e9put\u00e9 Arnel B\u00e9lizaire. Selon Washington, les deux hommes auraient jou\u00e9 un r\u00f4le jug\u00e9 \u00ab d\u00e9stabilisateur \u00bb dans le processus d\u00e9mocratique en\u2026","rel":"","context":"In &quot;SOCIETE&quot;","block_context":{"text":"SOCIETE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/societe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/d8b6ec45886449f2d9cb74bdc37233fc.jpeg?fit=1200%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/d8b6ec45886449f2d9cb74bdc37233fc.jpeg?fit=1200%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/d8b6ec45886449f2d9cb74bdc37233fc.jpeg?fit=1200%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/d8b6ec45886449f2d9cb74bdc37233fc.jpeg?fit=1200%2C1200&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/d8b6ec45886449f2d9cb74bdc37233fc.jpeg?fit=1200%2C1200&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6288,"url":"https:\/\/radioecoutefm.com\/index.php\/2026\/03\/15\/arrestation-de-lancien-depute-arnel-belizaire-a-petion-ville\/","url_meta":{"origin":5894,"position":1},"title":"Arrestation de l\u2019ancien d\u00e9put\u00e9 Arnel B\u00e9lizaire \u00e0 P\u00e9tion-Ville","author":"Ecoute FM","date":"15.03.2026","format":false,"excerpt":"Munie d\u2019un mandat d\u2019amener, la Direction Centrale de la Police Judiciaire (DCPJ) a proc\u00e9d\u00e9, ce samedi 14 mars 2026 vers 16 h 45, \u00e0 l\u2019arrestation de l\u2019ancien d\u00e9put\u00e9 Arnel B\u00e9lizaire \u00e0 l\u2019h\u00f4tel Oasis, dans la commune de P\u00e9tion-Ville. L\u2019ancien parlementaire a \u00e9t\u00e9 interpell\u00e9 lors d\u2019une op\u00e9ration men\u00e9e par des agents\u2026","rel":"","context":"In &quot;ARRESTATION&quot;","block_context":{"text":"ARRESTATION","link":"https:\/\/radioecoutefm.com\/index.php\/category\/arrestation\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2026\/03\/D3863D94-0AC2-4DD1-A61C-27848E7E6768.jpeg?fit=1200%2C577&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2026\/03\/D3863D94-0AC2-4DD1-A61C-27848E7E6768.jpeg?fit=1200%2C577&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2026\/03\/D3863D94-0AC2-4DD1-A61C-27848E7E6768.jpeg?fit=1200%2C577&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2026\/03\/D3863D94-0AC2-4DD1-A61C-27848E7E6768.jpeg?fit=1200%2C577&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2026\/03\/D3863D94-0AC2-4DD1-A61C-27848E7E6768.jpeg?fit=1200%2C577&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1784,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/03\/18\/nenel-cassy-dans-la-tourmente-le-commissaire-muscadin-exige-des-explications\/","url_meta":{"origin":5894,"position":2},"title":"Nenel Cassy dans la tourmente : Le commissaire Muscadin exige des explications","author":"Ecoute FM","date":"18.03.2025","format":false,"excerpt":"L\u2019ancien s\u00e9nateur des Nippes, Nenel Cassy, continue d\u2019\u00eatre au centre de la controverse apr\u00e8s sa pr\u00e9sentation au parquet de Port-au-Prince ce lundi 17 mars 2025. Alors qu\u2019il esp\u00e9rait clarifier sa situation judiciaire, une nouvelle d\u00e9claration du commissaire du gouvernement de Mirago\u00e2ne, Ma\u00eetre Jean Ernest Muscadin, vient raviver les tensions autour\u2026","rel":"","context":"In &quot;INSECURITE&quot;","block_context":{"text":"INSECURITE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/securite\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3535,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/04\/28\/jean-charles-moise-lance-un-ultimatum-au-conseil-presidentiel-de-transition\/","url_meta":{"origin":5894,"position":3},"title":"Jean-Charles Mo\u00efse lance un ultimatum au Conseil pr\u00e9sidentiel de transition !","author":"Ecoute FM","date":"28.04.2025","format":false,"excerpt":"En direct sur Radio Magik9 ce lundi 28 avril 2025, Jean-Charles Mo\u00efse, leader du parti Pitit Dessalines, a frapp\u00e9 fort : s\u2019il n\u2019obtient pas des d\u00e9cisions concr\u00e8tes dans les deux prochaines semaines, il promet de retirer son repr\u00e9sentant du Conseil pr\u00e9sidentiel de transition (CPT). \u00ab Nous ne sommes pas l\u00e0\u2026","rel":"","context":"In &quot;POLITIQUE&quot;","block_context":{"text":"POLITIQUE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/politique\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3650,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/05\/01\/arnel-belizaire-arrete-apres-une-altercation-a-jacmel\/","url_meta":{"origin":5894,"position":4},"title":"Arnel B\u00e9lizaire arr\u00eat\u00e9 apr\u00e8s une altercation \u00e0 Jacmel","author":"Ecoute FM","date":"01.05.2025","format":false,"excerpt":"L\u2019ex-d\u00e9put\u00e9 Arnel B\u00e9lizaire a \u00e9t\u00e9 arr\u00eat\u00e9 le 30 avril 2025 \u00e0 Jacmel apr\u00e8s avoir \u00e9t\u00e9 impliqu\u00e9 dans une violente dispute avec une commer\u00e7ante install\u00e9e pr\u00e8s de son h\u00f4tel. Selon des t\u00e9moins, l\u2019altercation a d\u00e9g\u00e9n\u00e9r\u00e9 lorsque l\u2019ex-parlementaire a agress\u00e9 la femme et caus\u00e9 des d\u00e9g\u00e2ts \u00e0 ses biens, provoquant une sc\u00e8ne\u2026","rel":"","context":"In &quot;JUSTICE&quot;","block_context":{"text":"JUSTICE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/interview\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2518,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/04\/09\/la-residence-de-lancien-senateur-dieuseul-simon-desras-incendiee-par-des-individus-armes\/","url_meta":{"origin":5894,"position":5},"title":"La r\u00e9sidence de l\u2019ancien s\u00e9nateur Dieuseul Simon Desras incendi\u00e9e par des individus arm\u00e9s","author":"Ecoute FM","date":"09.04.2025","format":false,"excerpt":"La violence qui ronge le pays n\u2019\u00e9pargne aucun recoin. Ce mardi, un nouvel acte d\u2019intimidation a \u00e9t\u00e9 enregistr\u00e9 dans la commune de Saut-d\u2019Eau, au Centre, o\u00f9 la maison de l\u2019ancien s\u00e9nateur Dieuseul Simon Desras a \u00e9t\u00e9 la cible d\u2019un incendie criminel perp\u00e9tr\u00e9 par des individus lourdement arm\u00e9s. Selon des t\u00e9moignages\u2026","rel":"","context":"In &quot;INSECURITE&quot;","block_context":{"text":"INSECURITE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/securite\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"authors":[{"term_id":15,"user_id":1,"is_guest":0,"slug":"borgellaattis","display_name":"Ecoute FM","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/a5369629745bf29c5deb65198d5e38aed1dc2c880c04b3b630ab3f6e8c623b70?s=96&d=mm&r=g","author_category":"","first_name":"","last_name":"","user_url":"http:\/\/radioecoutefm.com","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/posts\/5894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/comments?post=5894"}],"version-history":[{"count":1,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/posts\/5894\/revisions"}],"predecessor-version":[{"id":5899,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/posts\/5894\/revisions\/5899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/media\/5895"}],"wp:attachment":[{"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/media?parent=5894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/categories?post=5894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/tags?post=5894"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/ppma_author?post=5894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}