{"id":5391,"date":"2025-06-24T18:13:01","date_gmt":"2025-06-24T18:13:01","guid":{"rendered":"https:\/\/radioecoutefm.com\/?p=5391"},"modified":"2025-06-24T18:13:15","modified_gmt":"2025-06-24T18:13:15","slug":"david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti","status":"publish","type":"post","link":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/","title":{"rendered":"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\u00efti"},"content":{"rendered":"<p>L\u2019ancien pr\u00e9sident de la Cour supr\u00eame du Kenya, David Maraga, a lanc\u00e9 un avertissement s\u00e9v\u00e8re au pr\u00e9sident William Ruto, d\u00e9non\u00e7ant la r\u00e9pression violente des manifestations pacifiques dans le pays. Lors d\u2019une d\u00e9claration publique, Maraga a exprim\u00e9 son inqui\u00e9tude face \u00e0 la mont\u00e9e des violences contre les manifestants, orchestr\u00e9es selon lui par des groupes tol\u00e9r\u00e9s, voire soutenus par les autorit\u00e9s. Il a affirm\u00e9 que ces actions sapent les fondements d\u00e9mocratiques du Kenya et risquent de plonger le pays dans une situation de chaos comparable \u00e0 celle que conna\u00eet actuellement Ha\u00efti.<\/p>\n<p>Maraga a utilis\u00e9 l\u2019exemple ha\u00eftien comme une mise en garde, soulignant les cons\u00e9quences d\u2019un affaiblissement prolong\u00e9 de l\u2019\u00c9tat de droit et de la gouvernance. \u00ab S\u2019il vous pla\u00eet, ne nous envoyez pas dans l\u2019\u00e9tat d\u2019Ha\u00efti \u00bb, a-t-il d\u00e9clar\u00e9, appelant le gouvernement \u00e0 garantir le respect des libert\u00e9s fondamentales, notamment le droit de manifester pacifiquement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019ancien pr\u00e9sident de la Cour supr\u00eame du Kenya, David Maraga, a lanc\u00e9 un avertissement s\u00e9v\u00e8re au pr\u00e9sident William Ruto, d\u00e9non\u00e7ant la r\u00e9pression violente des manifestations pacifiques dans le pays. Lors d\u2019une d\u00e9claration publique, Maraga a exprim\u00e9 son inqui\u00e9tude face \u00e0 la mont\u00e9e des violences contre les manifestants, orchestr\u00e9es selon lui par des groupes tol\u00e9r\u00e9s, voire [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5392,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[46],"tags":[],"ppma_author":[15],"class_list":["post-5391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-international"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"L\u2019ancien pr\u00e9sident de la Cour supr\u00eame du Kenya, David Maraga, a lanc\u00e9 un avertissement s\u00e9v\u00e8re au pr\u00e9sident William Ruto, d\u00e9non\u00e7ant la r\u00e9pression violente des manifestations pacifiques dans le pays. Lors d\u2019une d\u00e9claration publique, Maraga a exprim\u00e9 son inqui\u00e9tude face \u00e0 la mont\u00e9e des violences contre les manifestants, orchestr\u00e9es selon lui par des groupes tol\u00e9r\u00e9s, voire\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Ecoute FM\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"RADIO ECOUTE FM \u2013 La Radio de toutes les ecoutes\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\u00efti \u2013 RADIO ECOUTE FM\" \/>\n\t\t<meta property=\"og:description\" content=\"L\u2019ancien pr\u00e9sident de la Cour supr\u00eame du Kenya, David Maraga, a lanc\u00e9 un avertissement s\u00e9v\u00e8re au pr\u00e9sident William Ruto, d\u00e9non\u00e7ant la r\u00e9pression violente des manifestations pacifiques dans le pays. Lors d\u2019une d\u00e9claration publique, Maraga a exprim\u00e9 son inqui\u00e9tude face \u00e0 la mont\u00e9e des violences contre les manifestants, orchestr\u00e9es selon lui par des groupes tol\u00e9r\u00e9s, voire\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-06-24T18:13:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-06-24T18:13:15+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\u00efti \u2013 RADIO ECOUTE FM\" \/>\n\t\t<meta name=\"twitter:description\" content=\"L\u2019ancien pr\u00e9sident de la Cour supr\u00eame du Kenya, David Maraga, a lanc\u00e9 un avertissement s\u00e9v\u00e8re au pr\u00e9sident William Ruto, d\u00e9non\u00e7ant la r\u00e9pression violente des manifestations pacifiques dans le pays. Lors d\u2019une d\u00e9claration publique, Maraga a exprim\u00e9 son inqui\u00e9tude face \u00e0 la mont\u00e9e des violences contre les manifestants, orchestr\u00e9es selon lui par des groupes tol\u00e9r\u00e9s, voire\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/24\\\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\\\/#blogposting\",\"name\":\"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\\u00efti \\u2013 RADIO ECOUTE FM\",\"headline\":\"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\\u00efti\",\"author\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radioecoutefm.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/IMG_2299.jpeg?fit=768%2C432&ssl=1\",\"width\":768,\"height\":432},\"datePublished\":\"2025-06-24T18:13:01+00:00\",\"dateModified\":\"2025-06-24T18:13:15+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/24\\\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/24\\\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\\\/#webpage\"},\"articleSection\":\"INTERNATIONAL, Ecoute FM\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/24\\\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/radioecoutefm.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/category\\\/international\\\/#listItem\",\"name\":\"INTERNATIONAL\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/category\\\/international\\\/#listItem\",\"position\":2,\"name\":\"INTERNATIONAL\",\"item\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/category\\\/international\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/24\\\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\\\/#listItem\",\"name\":\"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\\u00efti\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/24\\\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\\\/#listItem\",\"position\":3,\"name\":\"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\\u00efti\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/category\\\/international\\\/#listItem\",\"name\":\"INTERNATIONAL\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#organization\",\"name\":\"RADIO ECOUTE FM\",\"description\":\"La Radio de toutes les ecoutes\",\"url\":\"https:\\\/\\\/radioecoutefm.com\\\/\",\"email\":\"info@radioecoutefm.com\",\"telephone\":\"+15142173553\",\"foundingDate\":\"2019-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":0,\"maxValue\":9},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radioecoutefm.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-ECOIUTE1.png?fit=1600%2C800&ssl=1\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/24\\\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\\\/#organizationLogo\",\"width\":1600,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/24\\\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/#author\",\"url\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/\",\"name\":\"Ecoute FM\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/24\\\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5369629745bf29c5deb65198d5e38aed1dc2c880c04b3b630ab3f6e8c623b70?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Ecoute FM\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/24\\\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\\\/#webpage\",\"url\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/24\\\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\\\/\",\"name\":\"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\\u00efti \\u2013 RADIO ECOUTE FM\",\"description\":\"L\\u2019ancien pr\\u00e9sident de la Cour supr\\u00eame du Kenya, David Maraga, a lanc\\u00e9 un avertissement s\\u00e9v\\u00e8re au pr\\u00e9sident William Ruto, d\\u00e9non\\u00e7ant la r\\u00e9pression violente des manifestations pacifiques dans le pays. Lors d\\u2019une d\\u00e9claration publique, Maraga a exprim\\u00e9 son inqui\\u00e9tude face \\u00e0 la mont\\u00e9e des violences contre les manifestants, orchestr\\u00e9es selon lui par des groupes tol\\u00e9r\\u00e9s, voire\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/24\\\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radioecoutefm.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/IMG_2299.jpeg?fit=768%2C432&ssl=1\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/24\\\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\\\/#mainImage\",\"width\":768,\"height\":432},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/24\\\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\\\/#mainImage\"},\"datePublished\":\"2025-06-24T18:13:01+00:00\",\"dateModified\":\"2025-06-24T18:13:15+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#website\",\"url\":\"https:\\\/\\\/radioecoutefm.com\\\/\",\"name\":\"RADIO ECOUTE FM\",\"alternateName\":\"Ecoute FM\",\"description\":\"La Radio de toutes les ecoutes\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\u00efti \u2013 RADIO ECOUTE FM","description":"L\u2019ancien pr\u00e9sident de la Cour supr\u00eame du Kenya, David Maraga, a lanc\u00e9 un avertissement s\u00e9v\u00e8re au pr\u00e9sident William Ruto, d\u00e9non\u00e7ant la r\u00e9pression violente des manifestations pacifiques dans le pays. Lors d\u2019une d\u00e9claration publique, Maraga a exprim\u00e9 son inqui\u00e9tude face \u00e0 la mont\u00e9e des violences contre les manifestants, orchestr\u00e9es selon lui par des groupes tol\u00e9r\u00e9s, voire","canonical_url":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/#blogposting","name":"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\u00efti \u2013 RADIO ECOUTE FM","headline":"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\u00efti","author":{"@id":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/#author"},"publisher":{"@id":"https:\/\/radioecoutefm.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg?fit=768%2C432&ssl=1","width":768,"height":432},"datePublished":"2025-06-24T18:13:01+00:00","dateModified":"2025-06-24T18:13:15+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/#webpage"},"isPartOf":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/#webpage"},"articleSection":"INTERNATIONAL, Ecoute FM"},{"@type":"BreadcrumbList","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com#listItem","position":1,"name":"Home","item":"https:\/\/radioecoutefm.com","nextItem":{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/#listItem","name":"INTERNATIONAL"}},{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/#listItem","position":2,"name":"INTERNATIONAL","item":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/","nextItem":{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/#listItem","name":"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\u00efti"},"previousItem":{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/#listItem","position":3,"name":"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\u00efti","previousItem":{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/#listItem","name":"INTERNATIONAL"}}]},{"@type":"Organization","@id":"https:\/\/radioecoutefm.com\/#organization","name":"RADIO ECOUTE FM","description":"La Radio de toutes les ecoutes","url":"https:\/\/radioecoutefm.com\/","email":"info@radioecoutefm.com","telephone":"+15142173553","foundingDate":"2019-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":0,"maxValue":9},"logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2022\/02\/cropped-ECOIUTE1.png?fit=1600%2C800&ssl=1","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/#organizationLogo","width":1600,"height":800},"image":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/#author","url":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/","name":"Ecoute FM","image":{"@type":"ImageObject","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a5369629745bf29c5deb65198d5e38aed1dc2c880c04b3b630ab3f6e8c623b70?s=96&d=mm&r=g","width":96,"height":96,"caption":"Ecoute FM"}},{"@type":"WebPage","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/#webpage","url":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/","name":"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\u00efti \u2013 RADIO ECOUTE FM","description":"L\u2019ancien pr\u00e9sident de la Cour supr\u00eame du Kenya, David Maraga, a lanc\u00e9 un avertissement s\u00e9v\u00e8re au pr\u00e9sident William Ruto, d\u00e9non\u00e7ant la r\u00e9pression violente des manifestations pacifiques dans le pays. Lors d\u2019une d\u00e9claration publique, Maraga a exprim\u00e9 son inqui\u00e9tude face \u00e0 la mont\u00e9e des violences contre les manifestants, orchestr\u00e9es selon lui par des groupes tol\u00e9r\u00e9s, voire","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/radioecoutefm.com\/#website"},"breadcrumb":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/#breadcrumblist"},"author":{"@id":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/#author"},"creator":{"@id":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg?fit=768%2C432&ssl=1","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/#mainImage","width":768,"height":432},"primaryImageOfPage":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/#mainImage"},"datePublished":"2025-06-24T18:13:01+00:00","dateModified":"2025-06-24T18:13:15+00:00"},{"@type":"WebSite","@id":"https:\/\/radioecoutefm.com\/#website","url":"https:\/\/radioecoutefm.com\/","name":"RADIO ECOUTE FM","alternateName":"Ecoute FM","description":"La Radio de toutes les ecoutes","inLanguage":"en-US","publisher":{"@id":"https:\/\/radioecoutefm.com\/#organization"}}]},"og:locale":"en_US","og:site_name":"RADIO ECOUTE FM \u2013 La Radio de toutes les ecoutes","og:type":"article","og:title":"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\u00efti \u2013 RADIO ECOUTE FM","og:description":"L\u2019ancien pr\u00e9sident de la Cour supr\u00eame du Kenya, David Maraga, a lanc\u00e9 un avertissement s\u00e9v\u00e8re au pr\u00e9sident William Ruto, d\u00e9non\u00e7ant la r\u00e9pression violente des manifestations pacifiques dans le pays. Lors d\u2019une d\u00e9claration publique, Maraga a exprim\u00e9 son inqui\u00e9tude face \u00e0 la mont\u00e9e des violences contre les manifestants, orchestr\u00e9es selon lui par des groupes tol\u00e9r\u00e9s, voire","og:url":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/","og:image":"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg","og:image:secure_url":"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg","og:image:width":768,"og:image:height":432,"article:published_time":"2025-06-24T18:13:01+00:00","article:modified_time":"2025-06-24T18:13:15+00:00","twitter:card":"summary_large_image","twitter:title":"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\u00efti \u2013 RADIO ECOUTE FM","twitter:description":"L\u2019ancien pr\u00e9sident de la Cour supr\u00eame du Kenya, David Maraga, a lanc\u00e9 un avertissement s\u00e9v\u00e8re au pr\u00e9sident William Ruto, d\u00e9non\u00e7ant la r\u00e9pression violente des manifestations pacifiques dans le pays. Lors d\u2019une d\u00e9claration publique, Maraga a exprim\u00e9 son inqui\u00e9tude face \u00e0 la mont\u00e9e des violences contre les manifestants, orchestr\u00e9es selon lui par des groupes tol\u00e9r\u00e9s, voire","twitter:image":"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg"},"aioseo_meta_data":{"post_id":"5391","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-06-24 18:13:03","updated":"2025-06-24 18:21:15","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/radioecoutefm.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/radioecoutefm.com\/index.php\/category\/international\/\" title=\"INTERNATIONAL\">INTERNATIONAL<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDavid Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\u00efti\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/radioecoutefm.com"},{"label":"INTERNATIONAL","link":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/"},{"label":"David Maraga met en garde William Ruto : Ne transformez pas le Kenya en une autre Ha\u00efti","link":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/24\/david-maraga-met-en-garde-ruto-ne-transformez-pas-le-kenya-en-une-autre-haiti\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg?fit=768%2C432&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg?fit=768%2C432&ssl=1",768,432,false],"thumbnail":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg?fit=640%2C360&ssl=1",640,360,true],"large":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg?fit=640%2C360&ssl=1",640,360,true],"1536x1536":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg?fit=768%2C432&ssl=1",768,432,true],"2048x2048":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg?fit=768%2C432&ssl=1",768,432,true],"newsair-slider-full":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg?resize=768%2C432&ssl=1",768,432,true],"newsair-featured":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg?fit=768%2C432&ssl=1",768,432,true],"newsair-medium":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2299.jpeg?resize=720%2C380&ssl=1",720,380,true]},"uagb_author_info":{"display_name":"Ecoute FM","author_link":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/"},"uagb_comment_info":0,"uagb_excerpt":"L\u2019ancien pr\u00e9sident de la Cour supr\u00eame du Kenya, David Maraga, a lanc\u00e9 un avertissement s\u00e9v\u00e8re au pr\u00e9sident William Ruto, d\u00e9non\u00e7ant la r\u00e9pression violente des manifestations pacifiques dans le pays. Lors d\u2019une d\u00e9claration publique, Maraga a exprim\u00e9 son inqui\u00e9tude face \u00e0 la mont\u00e9e des violences contre les manifestants, orchestr\u00e9es selon lui par des groupes tol\u00e9r\u00e9s, voire&hellip;","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pgoyna-1oX","jetpack-related-posts":[{"id":3876,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/05\/06\/kenya-une-chaussure-lancee-en-pleine-foule-atteint-le-president-william-ruto-lors-dun-discours-a-migori\/","url_meta":{"origin":5391,"position":0},"title":"Kenya: Une chaussure lanc\u00e9e sur le pr\u00e9sident William Ruto en plein discours","author":"Ecoute FM","date":"06.05.2025","format":false,"excerpt":"Le pr\u00e9sident k\u00e9nyan William Ruto a \u00e9t\u00e9 la cible d\u2019un acte inattendu et spectaculaire dimanche \u00e0 Kuria West, dans le comt\u00e9 de Migori, lorsqu\u2019un individu a lanc\u00e9 une chaussure en sa direction alors qu\u2019il pronon\u00e7ait un discours devant une foule compacte. La sc\u00e8ne, film\u00e9e par les cam\u00e9ras avant une coupure\u2026","rel":"","context":"In &quot;INTERNATIONAL&quot;","block_context":{"text":"INTERNATIONAL","link":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/05\/DE869397-E264-4D74-BF2B-393694D01BC4.jpeg?fit=828%2C387&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/05\/DE869397-E264-4D74-BF2B-393694D01BC4.jpeg?fit=828%2C387&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/05\/DE869397-E264-4D74-BF2B-393694D01BC4.jpeg?fit=828%2C387&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/05\/DE869397-E264-4D74-BF2B-393694D01BC4.jpeg?fit=828%2C387&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":5790,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/09\/le-president-du-kenya-alerte-sur-la-fin-de-la-mission-en-haiti-et-presse-lonu-dassurer-une-transition\/","url_meta":{"origin":5391,"position":1},"title":"Le pr\u00e9sident du Kenya alerte sur la fin de la mission en Ha\u00efti et presse l\u2019ONU d\u2019assurer une transition","author":"Ecoute FM","date":"09.09.2025","format":false,"excerpt":"Alors que la mission internationale en Ha\u00efti approche de son \u00e9ch\u00e9ance, le pr\u00e9sident k\u00e9nyan William Ruto appelle le Conseil de s\u00e9curit\u00e9 des Nations Unies \u00e0 organiser une sortie responsable. Lors du deuxi\u00e8me sommet Afrique-CARICOM, tenu ce dimanche \u00e0 Addis-Abeba, en \u00c9thiopie, le pr\u00e9sident du Kenya, William Ruto, a exprim\u00e9 ses\u2026","rel":"","context":"In &quot;INTERNATIONAL&quot;","block_context":{"text":"INTERNATIONAL","link":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/ruto.jpg?fit=896%2C504&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/ruto.jpg?fit=896%2C504&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/ruto.jpg?fit=896%2C504&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/ruto.jpg?fit=896%2C504&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":5971,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/09\/23\/haiti-au-coeur-des-discussions-entre-mark-carney-et-william-ruto-a-new-york\/","url_meta":{"origin":5391,"position":2},"title":"Ha\u00efti au c\u0153ur des discussions entre Mark Carney et William Ruto \u00e0 New York","author":"Ecoute FM","date":"23.09.2025","format":false,"excerpt":"En marge de la 80e session de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale des Nations Unies, le premier ministre du Canada, Mark Carney, a rencontr\u00e9 ce lundi le pr\u00e9sident du Kenya, William Ruto. Les \u00e9changes ont largement port\u00e9 sur la situation s\u00e9curitaire en Ha\u00efti. Le premier ministre Carney a tenu \u00e0 remercier son homologue\u2026","rel":"","context":"In &quot;INTERNATIONAL&quot;","block_context":{"text":"INTERNATIONAL","link":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/IMG_2998.jpeg?fit=1170%2C748&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/IMG_2998.jpeg?fit=1170%2C748&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/IMG_2998.jpeg?fit=1170%2C748&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/IMG_2998.jpeg?fit=1170%2C748&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/09\/IMG_2998.jpeg?fit=1170%2C748&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":2057,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/03\/26\/le-secretaire-detat-americain-remercie-le-kenya-pour-son-leadership-en-matiere-de-paix-en-afrique-de-lest-alors-que-la-situation-en-haiti-reste-preoccupante\/","url_meta":{"origin":5391,"position":3},"title":"Le Kenya confront\u00e9 \u00e0 des d\u00e9fis en Ha\u00efti malgr\u00e9 son r\u00f4le de m\u00e9diateur en Afrique de l&#8217;Est","author":"Ecoute FM","date":"26.03.2025","format":false,"excerpt":"Le secr\u00e9taire d'\u00c9tat des \u00c9tats-Unis, Marco Rubio, a exprim\u00e9 sa reconnaissance envers le pr\u00e9sident du Kenya, William Ruto, pour le r\u00f4le crucial jou\u00e9 par son pays dans le maintien de la paix et de la s\u00e9curit\u00e9 en Afrique de l'Est. Dans une conversation r\u00e9cente, Rubio a salu\u00e9 l'engagement du Kenya\u2026","rel":"","context":"In &quot;INTERNATIONAL&quot;","block_context":{"text":"INTERNATIONAL","link":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/Rubio-and-Ruto.png?fit=700%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/Rubio-and-Ruto.png?fit=700%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/Rubio-and-Ruto.png?fit=700%2C400&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/Rubio-and-Ruto.png?fit=700%2C400&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":5427,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/26\/mission-en-haiti-le-kenya-menace-de-se-retirer-face-au-manque-de-soutien\/","url_meta":{"origin":5391,"position":4},"title":"Mission en Ha\u00efti : le Kenya menace de se retirer face au manque de soutien","author":"Ecoute FM","date":"26.06.2025","format":false,"excerpt":"La participation du Kenya \u00e0 la Mission multinationale de soutien \u00e0 la s\u00e9curit\u00e9 (MMSS) en Ha\u00efti est d\u00e9sormais incertaine. Le pr\u00e9sident k\u00e9nyan William Ruto a d\u00e9clar\u00e9 que son pays pourrait se retirer de l\u2019op\u00e9ration en raison du faible engagement de la communaut\u00e9 internationale. Ce signal d\u2019alerte remet en question l\u2019avenir\u2026","rel":"","context":"In &quot;INTERNATIONAL&quot;","block_context":{"text":"INTERNATIONAL","link":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2305.jpeg?fit=976%2C549&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2305.jpeg?fit=976%2C549&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2305.jpeg?fit=976%2C549&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/IMG_2305.jpeg?fit=976%2C549&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2777,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/04\/14\/haiti-au-bord-du-gouffre-la-caricom-met-en-garde-contre-une-prise-de-pouvoir-par-les-gangs\/","url_meta":{"origin":5391,"position":5},"title":"Ha\u00efti au bord du gouffre : la CARICOM met en garde contre une prise de pouvoir par les gangs","author":"Ecoute FM","date":"14.04.2025","format":false,"excerpt":"Alors que la situation s\u00e9curitaire en Ha\u00efti continue de se d\u00e9t\u00e9riorer, la Communaut\u00e9 des Cara\u00efbes (CARICOM) a lanc\u00e9 un appel urgent \u00e0 la communaut\u00e9 internationale pour \u00e9viter une nouvelle escalade de la violence. Dans une d\u00e9claration publi\u00e9e ce 13 avril 2025, l'organisation r\u00e9gionale se dit \u00ab profond\u00e9ment pr\u00e9occup\u00e9e \u00bb par\u2026","rel":"","context":"In &quot;POLITIQUE&quot;","block_context":{"text":"POLITIQUE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/politique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/04\/caricom.jpg?fit=686%2C386&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/04\/caricom.jpg?fit=686%2C386&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/04\/caricom.jpg?fit=686%2C386&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"authors":[{"term_id":15,"user_id":1,"is_guest":0,"slug":"borgellaattis","display_name":"Ecoute FM","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/a5369629745bf29c5deb65198d5e38aed1dc2c880c04b3b630ab3f6e8c623b70?s=96&d=mm&r=g","author_category":"","first_name":"","last_name":"","user_url":"http:\/\/radioecoutefm.com","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/posts\/5391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/comments?post=5391"}],"version-history":[{"count":1,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/posts\/5391\/revisions"}],"predecessor-version":[{"id":5396,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/posts\/5391\/revisions\/5396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/media\/5392"}],"wp:attachment":[{"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/media?parent=5391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/categories?post=5391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/tags?post=5391"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/ppma_author?post=5391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}