{"id":5241,"date":"2025-06-20T23:19:21","date_gmt":"2025-06-20T23:19:21","guid":{"rendered":"https:\/\/radioecoutefm.com\/?p=5241"},"modified":"2025-06-20T23:19:21","modified_gmt":"2025-06-20T23:19:21","slug":"haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders","status":"publish","type":"post","link":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/","title":{"rendered":"Ha\u00efti au bord du gouffre : l\u2019appel lucide de Sir Ronald Sanders"},"content":{"rendered":"<p>Dans un monde satur\u00e9 de crises, la trag\u00e9die ha\u00eftienne se poursuit dans un silence assourdissant. Pourtant, dans un article courageux et \u00e9clairant, Sir Ronald Sanders, ambassadeur d\u2019Antigua-et-Barbuda aupr\u00e8s des \u00c9tats-Unis et de l\u2019OEA, nous oblige \u00e0 regarder la r\u00e9alit\u00e9 en face : Ha\u00efti s\u2019effondre. Et les Ha\u00eftiens, d\u00e9j\u00e0 parmi les plus vuln\u00e9rables de l\u2019h\u00e9misph\u00e8re, sont abandonn\u00e9s \u00e0 leur sort.<\/p>\n<p>Sir Ronald Sanders ne se contente pas de d\u00e9crire les faits. Il les documente avec pr\u00e9cision. Plus de 4 400 meurtres entre avril 2024 et mars 2025, une capitale contr\u00f4l\u00e9e \u00e0 80 % par des gangs, des femmes victimes de violences sexuelles en masse, une justice qui fonctionne depuis des maisons de fortune, et une transition politique qui n\u2019a rien chang\u00e9, sinon aggrav\u00e9 la situation.<\/p>\n<p>Selon lui, le Conseil pr\u00e9sidentiel de transition (CPT), mis en place en avril 2024 sans l\u00e9gitimit\u00e9 d\u00e9mocratique, a profond\u00e9ment \u00e9chou\u00e9. Il s\u2019appuie notamment sur le rapport accablant du R\u00e9seau National de D\u00e9fense des Droits Humains (RNDDH), qui dresse un tableau accablant d\u2019impunit\u00e9, de corruption et d\u2019incomp\u00e9tence. Sanders souligne que sur treize massacres recens\u00e9s, un seul a donn\u00e9 lieu \u00e0 des poursuites. Le reste est laiss\u00e9 \u00e0 l\u2019oubli, et aux larmes des familles.<\/p>\n<p>Mais Sir Ronald Sanders ne s\u2019arr\u00eate pas \u00e0 la critique : il propose une analyse strat\u00e9gique claire et courageuse. Il affirme sans d\u00e9tour que, sans recours \u00e0 la force, aucune am\u00e9lioration s\u00e9curitaire ne sera possible. Mais il est tout aussi lucide : une telle force internationale n\u2019aura jamais l\u2019aval du Conseil de s\u00e9curit\u00e9 de l\u2019ONU, bloqu\u00e9 par les jeux g\u00e9opolitiques, ni celui de l\u2019OEA, limit\u00e9 par sa charte. Le statu quo est donc condamn\u00e9 \u00e0 perdurer si l\u2019on ne sort pas des cadres habituels.<\/p>\n<p>C\u2019est pourquoi Sir Ronald Sanders avance l\u2019id\u00e9e, certes controvers\u00e9e mais n\u00e9cessaire, d\u2019un dialogue avec les chefs de gangs. Non pour leur donner du pouvoir, insiste-t-il, mais pour explorer des incitations \u00e0 la coop\u00e9ration, dans le but de r\u00e9tablir l\u2019ordre et de pr\u00e9parer un avenir politique cr\u00e9dible. Il rappelle que dans d&#8217;autres r\u00e9gions du monde, des conflits internes ont trouv\u00e9 une issue non pas par la violence seule, mais par la diplomatie de l\u2019extr\u00eame.<\/p>\n<p>Il appelle aussi \u00e0 une coop\u00e9ration renforc\u00e9e entre l\u2019ONU, l\u2019OEA, les membres influents du Conseil de s\u00e9curit\u00e9 et le CPT, pour \u00e9tablir un plan de stabilisation \u00e0 court terme, coupl\u00e9 \u00e0 une transformation \u00e9conomique \u00e0 long terme. C\u2019est cette vision \u00e0 deux volets \u2013 s\u00e9curit\u00e9 imm\u00e9diate et d\u00e9veloppement durable \u2013 que Sanders consid\u00e8re comme essentielle.<\/p>\n<p>Dans un contexte o\u00f9 certains pr\u00e9f\u00e8rent des solutions militaris\u00e9es risqu\u00e9es \u2013 comme le recours \u00e0 des mercenaires dirig\u00e9s par Erik Prince utilisant des drones meurtriers \u2013 Sir Ronald Sanders met en garde : cela pourrait entra\u00eener une escalade incontr\u00f4lable, les gangs pouvant riposter avec les m\u00eames moyens technologiques.<\/p>\n<p>Sir Ronald Sanders, fort de son exp\u00e9rience \u00e0 la t\u00eate de la mission de l\u2019OEA en Ha\u00efti en 2016, parle avec une autorit\u00e9 que peu peuvent revendiquer. Il nous rappelle que, sans une diplomatie audacieuse et un leadership r\u00e9gional fort, Ha\u00efti restera prisonni\u00e8re de la violence, de l\u2019instabilit\u00e9 et de l\u2019abandon international.<\/p>\n<p>L\u2019heure n\u2019est plus \u00e0 l\u2019attentisme. Il est temps d\u2019\u00e9couter les voix lucides et exp\u00e9riment\u00e9es comme celle de Sir Ronald Sanders, qui ne se contente pas de diagnostiquer, mais trace une voie \u2013 difficile, mais possible \u2013 pour sortir Ha\u00efti de la spirale infernale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans un monde satur\u00e9 de crises, la trag\u00e9die ha\u00eftienne se poursuit dans un silence assourdissant. Pourtant, dans un article courageux et \u00e9clairant, Sir Ronald Sanders, ambassadeur d\u2019Antigua-et-Barbuda aupr\u00e8s des \u00c9tats-Unis et de l\u2019OEA, nous oblige \u00e0 regarder la r\u00e9alit\u00e9 en face : Ha\u00efti s\u2019effondre. Et les Ha\u00eftiens, d\u00e9j\u00e0 parmi les plus vuln\u00e9rables de l\u2019h\u00e9misph\u00e8re, sont [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[8],"tags":[],"ppma_author":[15],"class_list":["post-5241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politique"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Dans un monde satur\u00e9 de crises, la trag\u00e9die ha\u00eftienne se poursuit dans un silence assourdissant. Pourtant, dans un article courageux et \u00e9clairant, Sir Ronald Sanders, ambassadeur d\u2019Antigua-et-Barbuda aupr\u00e8s des \u00c9tats-Unis et de l\u2019OEA, nous oblige \u00e0 regarder la r\u00e9alit\u00e9 en face : Ha\u00efti s\u2019effondre. Et les Ha\u00eftiens, d\u00e9j\u00e0 parmi les plus vuln\u00e9rables de l\u2019h\u00e9misph\u00e8re, sont\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Ecoute FM\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"RADIO ECOUTE FM \u2013 La Radio de toutes les ecoutes\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ha\u00efti au bord du gouffre : l\u2019appel lucide de Sir Ronald Sanders \u2013 RADIO ECOUTE FM\" \/>\n\t\t<meta property=\"og:description\" content=\"Dans un monde satur\u00e9 de crises, la trag\u00e9die ha\u00eftienne se poursuit dans un silence assourdissant. Pourtant, dans un article courageux et \u00e9clairant, Sir Ronald Sanders, ambassadeur d\u2019Antigua-et-Barbuda aupr\u00e8s des \u00c9tats-Unis et de l\u2019OEA, nous oblige \u00e0 regarder la r\u00e9alit\u00e9 en face : Ha\u00efti s\u2019effondre. Et les Ha\u00eftiens, d\u00e9j\u00e0 parmi les plus vuln\u00e9rables de l\u2019h\u00e9misph\u00e8re, sont\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-06-20T23:19:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-06-20T23:19:21+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ha\u00efti au bord du gouffre : l\u2019appel lucide de Sir Ronald Sanders \u2013 RADIO ECOUTE FM\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Dans un monde satur\u00e9 de crises, la trag\u00e9die ha\u00eftienne se poursuit dans un silence assourdissant. Pourtant, dans un article courageux et \u00e9clairant, Sir Ronald Sanders, ambassadeur d\u2019Antigua-et-Barbuda aupr\u00e8s des \u00c9tats-Unis et de l\u2019OEA, nous oblige \u00e0 regarder la r\u00e9alit\u00e9 en face : Ha\u00efti s\u2019effondre. Et les Ha\u00eftiens, d\u00e9j\u00e0 parmi les plus vuln\u00e9rables de l\u2019h\u00e9misph\u00e8re, sont\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/20\\\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\\\/#blogposting\",\"name\":\"Ha\\u00efti au bord du gouffre : l\\u2019appel lucide de Sir Ronald Sanders \\u2013 RADIO ECOUTE FM\",\"headline\":\"Ha\\u00efti au bord du gouffre : l\\u2019appel lucide de Sir Ronald Sanders\",\"author\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radioecoutefm.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/gang.webp?fit=1200%2C720&ssl=1\",\"width\":1200,\"height\":720},\"datePublished\":\"2025-06-20T23:19:21+00:00\",\"dateModified\":\"2025-06-20T23:19:21+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/20\\\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/20\\\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\\\/#webpage\"},\"articleSection\":\"POLITIQUE, Ecoute FM\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/20\\\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/radioecoutefm.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/category\\\/politique\\\/#listItem\",\"name\":\"POLITIQUE\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/category\\\/politique\\\/#listItem\",\"position\":2,\"name\":\"POLITIQUE\",\"item\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/category\\\/politique\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/20\\\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\\\/#listItem\",\"name\":\"Ha\\u00efti au bord du gouffre : l\\u2019appel lucide de Sir Ronald Sanders\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/20\\\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\\\/#listItem\",\"position\":3,\"name\":\"Ha\\u00efti au bord du gouffre : l\\u2019appel lucide de Sir Ronald Sanders\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/category\\\/politique\\\/#listItem\",\"name\":\"POLITIQUE\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#organization\",\"name\":\"RADIO ECOUTE FM\",\"description\":\"La Radio de toutes les ecoutes\",\"url\":\"https:\\\/\\\/radioecoutefm.com\\\/\",\"email\":\"info@radioecoutefm.com\",\"telephone\":\"+15142173553\",\"foundingDate\":\"2019-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":0,\"maxValue\":9},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radioecoutefm.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-ECOIUTE1.png?fit=1600%2C800&ssl=1\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/20\\\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\\\/#organizationLogo\",\"width\":1600,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/20\\\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/#author\",\"url\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/\",\"name\":\"Ecoute FM\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/20\\\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a5369629745bf29c5deb65198d5e38aed1dc2c880c04b3b630ab3f6e8c623b70?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Ecoute FM\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/20\\\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\\\/#webpage\",\"url\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/20\\\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\\\/\",\"name\":\"Ha\\u00efti au bord du gouffre : l\\u2019appel lucide de Sir Ronald Sanders \\u2013 RADIO ECOUTE FM\",\"description\":\"Dans un monde satur\\u00e9 de crises, la trag\\u00e9die ha\\u00eftienne se poursuit dans un silence assourdissant. Pourtant, dans un article courageux et \\u00e9clairant, Sir Ronald Sanders, ambassadeur d\\u2019Antigua-et-Barbuda aupr\\u00e8s des \\u00c9tats-Unis et de l\\u2019OEA, nous oblige \\u00e0 regarder la r\\u00e9alit\\u00e9 en face : Ha\\u00efti s\\u2019effondre. Et les Ha\\u00eftiens, d\\u00e9j\\u00e0 parmi les plus vuln\\u00e9rables de l\\u2019h\\u00e9misph\\u00e8re, sont\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/20\\\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/author\\\/borgellaattis\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/radioecoutefm.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/gang.webp?fit=1200%2C720&ssl=1\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/20\\\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\\\/#mainImage\",\"width\":1200,\"height\":720},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/index.php\\\/2025\\\/06\\\/20\\\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\\\/#mainImage\"},\"datePublished\":\"2025-06-20T23:19:21+00:00\",\"dateModified\":\"2025-06-20T23:19:21+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#website\",\"url\":\"https:\\\/\\\/radioecoutefm.com\\\/\",\"name\":\"RADIO ECOUTE FM\",\"alternateName\":\"Ecoute FM\",\"description\":\"La Radio de toutes les ecoutes\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioecoutefm.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ha\u00efti au bord du gouffre : l\u2019appel lucide de Sir Ronald Sanders \u2013 RADIO ECOUTE FM","description":"Dans un monde satur\u00e9 de crises, la trag\u00e9die ha\u00eftienne se poursuit dans un silence assourdissant. Pourtant, dans un article courageux et \u00e9clairant, Sir Ronald Sanders, ambassadeur d\u2019Antigua-et-Barbuda aupr\u00e8s des \u00c9tats-Unis et de l\u2019OEA, nous oblige \u00e0 regarder la r\u00e9alit\u00e9 en face : Ha\u00efti s\u2019effondre. Et les Ha\u00eftiens, d\u00e9j\u00e0 parmi les plus vuln\u00e9rables de l\u2019h\u00e9misph\u00e8re, sont","canonical_url":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/#blogposting","name":"Ha\u00efti au bord du gouffre : l\u2019appel lucide de Sir Ronald Sanders \u2013 RADIO ECOUTE FM","headline":"Ha\u00efti au bord du gouffre : l\u2019appel lucide de Sir Ronald Sanders","author":{"@id":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/#author"},"publisher":{"@id":"https:\/\/radioecoutefm.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp?fit=1200%2C720&ssl=1","width":1200,"height":720},"datePublished":"2025-06-20T23:19:21+00:00","dateModified":"2025-06-20T23:19:21+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/#webpage"},"isPartOf":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/#webpage"},"articleSection":"POLITIQUE, Ecoute FM"},{"@type":"BreadcrumbList","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com#listItem","position":1,"name":"Home","item":"https:\/\/radioecoutefm.com","nextItem":{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/category\/politique\/#listItem","name":"POLITIQUE"}},{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/category\/politique\/#listItem","position":2,"name":"POLITIQUE","item":"https:\/\/radioecoutefm.com\/index.php\/category\/politique\/","nextItem":{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/#listItem","name":"Ha\u00efti au bord du gouffre : l\u2019appel lucide de Sir Ronald Sanders"},"previousItem":{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/#listItem","position":3,"name":"Ha\u00efti au bord du gouffre : l\u2019appel lucide de Sir Ronald Sanders","previousItem":{"@type":"ListItem","@id":"https:\/\/radioecoutefm.com\/index.php\/category\/politique\/#listItem","name":"POLITIQUE"}}]},{"@type":"Organization","@id":"https:\/\/radioecoutefm.com\/#organization","name":"RADIO ECOUTE FM","description":"La Radio de toutes les ecoutes","url":"https:\/\/radioecoutefm.com\/","email":"info@radioecoutefm.com","telephone":"+15142173553","foundingDate":"2019-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":0,"maxValue":9},"logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2022\/02\/cropped-ECOIUTE1.png?fit=1600%2C800&ssl=1","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/#organizationLogo","width":1600,"height":800},"image":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/#author","url":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/","name":"Ecoute FM","image":{"@type":"ImageObject","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a5369629745bf29c5deb65198d5e38aed1dc2c880c04b3b630ab3f6e8c623b70?s=96&d=mm&r=g","width":96,"height":96,"caption":"Ecoute FM"}},{"@type":"WebPage","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/#webpage","url":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/","name":"Ha\u00efti au bord du gouffre : l\u2019appel lucide de Sir Ronald Sanders \u2013 RADIO ECOUTE FM","description":"Dans un monde satur\u00e9 de crises, la trag\u00e9die ha\u00eftienne se poursuit dans un silence assourdissant. Pourtant, dans un article courageux et \u00e9clairant, Sir Ronald Sanders, ambassadeur d\u2019Antigua-et-Barbuda aupr\u00e8s des \u00c9tats-Unis et de l\u2019OEA, nous oblige \u00e0 regarder la r\u00e9alit\u00e9 en face : Ha\u00efti s\u2019effondre. Et les Ha\u00eftiens, d\u00e9j\u00e0 parmi les plus vuln\u00e9rables de l\u2019h\u00e9misph\u00e8re, sont","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/radioecoutefm.com\/#website"},"breadcrumb":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/#breadcrumblist"},"author":{"@id":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/#author"},"creator":{"@id":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp?fit=1200%2C720&ssl=1","@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/#mainImage","width":1200,"height":720},"primaryImageOfPage":{"@id":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/#mainImage"},"datePublished":"2025-06-20T23:19:21+00:00","dateModified":"2025-06-20T23:19:21+00:00"},{"@type":"WebSite","@id":"https:\/\/radioecoutefm.com\/#website","url":"https:\/\/radioecoutefm.com\/","name":"RADIO ECOUTE FM","alternateName":"Ecoute FM","description":"La Radio de toutes les ecoutes","inLanguage":"en-US","publisher":{"@id":"https:\/\/radioecoutefm.com\/#organization"}}]},"og:locale":"en_US","og:site_name":"RADIO ECOUTE FM \u2013 La Radio de toutes les ecoutes","og:type":"article","og:title":"Ha\u00efti au bord du gouffre : l\u2019appel lucide de Sir Ronald Sanders \u2013 RADIO ECOUTE FM","og:description":"Dans un monde satur\u00e9 de crises, la trag\u00e9die ha\u00eftienne se poursuit dans un silence assourdissant. Pourtant, dans un article courageux et \u00e9clairant, Sir Ronald Sanders, ambassadeur d\u2019Antigua-et-Barbuda aupr\u00e8s des \u00c9tats-Unis et de l\u2019OEA, nous oblige \u00e0 regarder la r\u00e9alit\u00e9 en face : Ha\u00efti s\u2019effondre. Et les Ha\u00eftiens, d\u00e9j\u00e0 parmi les plus vuln\u00e9rables de l\u2019h\u00e9misph\u00e8re, sont","og:url":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/","og:image":"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp","og:image:secure_url":"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp","og:image:width":1200,"og:image:height":720,"article:published_time":"2025-06-20T23:19:21+00:00","article:modified_time":"2025-06-20T23:19:21+00:00","twitter:card":"summary_large_image","twitter:title":"Ha\u00efti au bord du gouffre : l\u2019appel lucide de Sir Ronald Sanders \u2013 RADIO ECOUTE FM","twitter:description":"Dans un monde satur\u00e9 de crises, la trag\u00e9die ha\u00eftienne se poursuit dans un silence assourdissant. Pourtant, dans un article courageux et \u00e9clairant, Sir Ronald Sanders, ambassadeur d\u2019Antigua-et-Barbuda aupr\u00e8s des \u00c9tats-Unis et de l\u2019OEA, nous oblige \u00e0 regarder la r\u00e9alit\u00e9 en face : Ha\u00efti s\u2019effondre. Et les Ha\u00eftiens, d\u00e9j\u00e0 parmi les plus vuln\u00e9rables de l\u2019h\u00e9misph\u00e8re, sont","twitter:image":"https:\/\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp"},"aioseo_meta_data":{"post_id":"5241","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-06-20 23:19:22","updated":"2025-06-20 23:30:58","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/radioecoutefm.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/radioecoutefm.com\/index.php\/category\/politique\/\" title=\"POLITIQUE\">POLITIQUE<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHa\u00efti au bord du gouffre : l\u2019appel lucide de Sir Ronald Sanders\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/radioecoutefm.com"},{"label":"POLITIQUE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/politique\/"},{"label":"Ha\u00efti au bord du gouffre : l\u2019appel lucide de Sir Ronald Sanders","link":"https:\/\/radioecoutefm.com\/index.php\/2025\/06\/20\/haiti-au-bord-du-gouffre-lappel-lucide-de-sir-ronald-sanders\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp?fit=1200%2C720&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp?fit=1200%2C720&ssl=1",1200,720,false],"thumbnail":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp?fit=300%2C180&ssl=1",300,180,true],"medium_large":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp?fit=640%2C384&ssl=1",640,384,true],"large":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp?fit=640%2C384&ssl=1",640,384,true],"1536x1536":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp?fit=1200%2C720&ssl=1",1200,720,true],"2048x2048":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp?fit=1200%2C720&ssl=1",1200,720,true],"newsair-slider-full":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp?resize=1200%2C720&ssl=1",1200,720,true],"newsair-featured":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp?fit=1024%2C614&ssl=1",1024,614,true],"newsair-medium":["https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/06\/gang.webp?resize=720%2C380&ssl=1",720,380,true]},"uagb_author_info":{"display_name":"Ecoute FM","author_link":"https:\/\/radioecoutefm.com\/index.php\/author\/borgellaattis\/"},"uagb_comment_info":0,"uagb_excerpt":"Dans un monde satur\u00e9 de crises, la trag\u00e9die ha\u00eftienne se poursuit dans un silence assourdissant. Pourtant, dans un article courageux et \u00e9clairant, Sir Ronald Sanders, ambassadeur d\u2019Antigua-et-Barbuda aupr\u00e8s des \u00c9tats-Unis et de l\u2019OEA, nous oblige \u00e0 regarder la r\u00e9alit\u00e9 en face : Ha\u00efti s\u2019effondre. Et les Ha\u00eftiens, d\u00e9j\u00e0 parmi les plus vuln\u00e9rables de l\u2019h\u00e9misph\u00e8re, sont&hellip;","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pgoyna-1mx","jetpack-related-posts":[{"id":1328,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/03\/05\/haiti-instabilite-politique-et-violence-grandissante-le-conseil-presidentiel-de-transition-dans-loeil-du-cyclone\/","url_meta":{"origin":5241,"position":0},"title":"Ha\u00efti : Instabilit\u00e9 politique et violence grandissante, le Conseil Pr\u00e9sidentiel de Transition dans l\u2019\u0153il du cyclone","author":"Ecoute FM","date":"05.03.2025","format":false,"excerpt":"Le climat politique en Ha\u00efti, d\u00e9j\u00e0 fragile, devient de plus en plus tendu alors que le pays est en proie \u00e0 une crise profonde marqu\u00e9e par l\u2019intensification des activit\u00e9s des gangs arm\u00e9s. Dans ce contexte difficile, le Conseil Pr\u00e9sidentiel de Transition (CTP) d'Ha\u00efti semble se retrouver sous une pression croissante,\u2026","rel":"","context":"In &quot;POLITIQUE&quot;","block_context":{"text":"POLITIQUE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/politique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/9-membres-du-CPT.jpg?fit=550%2C370&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/9-membres-du-CPT.jpg?fit=550%2C370&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/9-membres-du-CPT.jpg?fit=550%2C370&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":1978,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/03\/24\/marco-rubio-en-tournee-dans-les-caraibes-haiti-au-centre-des-preoccupations\/","url_meta":{"origin":5241,"position":1},"title":"Marco Rubio en tourn\u00e9e dans les Cara\u00efbes : Ha\u00efti au centre des pr\u00e9occupations","author":"Ecoute FM","date":"24.03.2025","format":false,"excerpt":"Le secr\u00e9taire d\u2019\u00c9tat am\u00e9ricain Marco Rubio entame cette semaine sa premi\u00e8re tourn\u00e9e officielle dans les Cara\u00efbes, \u00e0 un moment o\u00f9 la situation en Ha\u00efti suscite de vives inqui\u00e9tudes parmi les dirigeants de la r\u00e9gion. Au cours de son voyage, Rubio se rendra en Jama\u00efque, o\u00f9 il sera re\u00e7u par le\u2026","rel":"","context":"In &quot;INSECURITE&quot;","block_context":{"text":"INSECURITE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/securite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/IMG_1473.png?fit=512%2C342&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2097,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/03\/26\/haiti-au-coeur-des-debats-pourquoi-marco-rubio-na-t-il-jamais-visite-le-pays-malgre-ses-voyages-dans-les-caraibes\/","url_meta":{"origin":5241,"position":2},"title":"Ha\u00efti au c\u0153ur des d\u00e9bats, pourquoi Marco Rubio n\u2019a-t-il jamais visit\u00e9 le pays malgr\u00e9 ses voyages dans les Cara\u00efbes ?","author":"Ecoute FM","date":"26.03.2025","format":false,"excerpt":"Marco Rubio, s\u00e9nateur am\u00e9ricain et figure importante en mati\u00e8re de politique \u00e9trang\u00e8re, a effectu\u00e9 deux voyages dans les Cara\u00efbes r\u00e9cemment, mais il n\u2019a toujours pas visit\u00e9 Ha\u00efti, malgr\u00e9 la situation critique qui y pr\u00e9vaut. Ces d\u00e9placements en r\u00e9gion ont principalement \u00e9t\u00e9 ax\u00e9s sur la consolidation des relations entre les \u00c9tats-Unis\u2026","rel":"","context":"In &quot;INTERNATIONAL&quot;","block_context":{"text":"INTERNATIONAL","link":"https:\/\/radioecoutefm.com\/index.php\/category\/international\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/03\/RUBIO.png?fit=515%2C322&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2777,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/04\/14\/haiti-au-bord-du-gouffre-la-caricom-met-en-garde-contre-une-prise-de-pouvoir-par-les-gangs\/","url_meta":{"origin":5241,"position":3},"title":"Ha\u00efti au bord du gouffre : la CARICOM met en garde contre une prise de pouvoir par les gangs","author":"Ecoute FM","date":"14.04.2025","format":false,"excerpt":"Alors que la situation s\u00e9curitaire en Ha\u00efti continue de se d\u00e9t\u00e9riorer, la Communaut\u00e9 des Cara\u00efbes (CARICOM) a lanc\u00e9 un appel urgent \u00e0 la communaut\u00e9 internationale pour \u00e9viter une nouvelle escalade de la violence. Dans une d\u00e9claration publi\u00e9e ce 13 avril 2025, l'organisation r\u00e9gionale se dit \u00ab profond\u00e9ment pr\u00e9occup\u00e9e \u00bb par\u2026","rel":"","context":"In &quot;POLITIQUE&quot;","block_context":{"text":"POLITIQUE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/politique\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/04\/caricom.jpg?fit=686%2C386&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/04\/caricom.jpg?fit=686%2C386&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/04\/caricom.jpg?fit=686%2C386&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":1510,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/03\/11\/haiti-linsecurite-frappe-a-nouveau-le-dr-laurent-bauger-abattu-a-delmas-31\/","url_meta":{"origin":5241,"position":4},"title":"Ha\u00efti : L&#8217;ins\u00e9curit\u00e9 frappe \u00e0 nouveau, le Dr Laurent Bauger abattu \u00e0 Delmas 31","author":"Ecoute FM","date":"11.03.2025","format":false,"excerpt":"Ce mardi matin, Ha\u00efti a \u00e9t\u00e9 secou\u00e9e par une nouvelle manifestation de la violence qui ravage le pays. Le Dr Laurent Bauger, ancien Secr\u00e9taire d\u2019\u00c9tat \u00e0 la Population sous le gouvernement d\u2019Ariel Henry, a \u00e9t\u00e9 abattu en plein jour par des individus arm\u00e9s \u00e0 Delmas 31, un quartier de Port-au-Prince.\u2026","rel":"","context":"In &quot;INSECURITE&quot;","block_context":{"text":"INSECURITE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/securite\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2783,"url":"https:\/\/radioecoutefm.com\/index.php\/2025\/04\/14\/haiti-les-gangs-menacent-de-renverser-le-conseil-de-transition-washington-reagit-et-soutient-la-caricom\/","url_meta":{"origin":5241,"position":5},"title":"Ha\u00efti : les gangs menacent de renverser le Conseil de transition, Washington r\u00e9agit et soutient la CARICOM","author":"Ecoute FM","date":"14.04.2025","format":false,"excerpt":"Alors que la pression des groupes arm\u00e9s se fait de plus en plus forte \u00e0 Port-au-Prince, les \u00c9tats-Unis montent au cr\u00e9neau. Par la voix de son ambassade en Ha\u00efti, Washington a exprim\u00e9 son soutien \u00e0 la d\u00e9claration de la CARICOM qui condamne fermement les menaces visant \u00e0 faire tomber le\u2026","rel":"","context":"In &quot;INSECURITE&quot;","block_context":{"text":"INSECURITE","link":"https:\/\/radioecoutefm.com\/index.php\/category\/securite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/04\/us-embassy.jpg?fit=750%2C450&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/04\/us-embassy.jpg?fit=750%2C450&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/04\/us-embassy.jpg?fit=750%2C450&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/radioecoutefm.com\/wp-content\/uploads\/2025\/04\/us-embassy.jpg?fit=750%2C450&ssl=1&resize=700%2C400 2x"},"classes":[]}],"authors":[{"term_id":15,"user_id":1,"is_guest":0,"slug":"borgellaattis","display_name":"Ecoute FM","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/a5369629745bf29c5deb65198d5e38aed1dc2c880c04b3b630ab3f6e8c623b70?s=96&d=mm&r=g","author_category":"","first_name":"","last_name":"","user_url":"http:\/\/radioecoutefm.com","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/posts\/5241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/comments?post=5241"}],"version-history":[{"count":2,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/posts\/5241\/revisions"}],"predecessor-version":[{"id":5247,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/posts\/5241\/revisions\/5247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/media\/5242"}],"wp:attachment":[{"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/media?parent=5241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/categories?post=5241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/tags?post=5241"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/radioecoutefm.com\/index.php\/wp-json\/wp\/v2\/ppma_author?post=5241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}